{"id":1046,"date":"2010-10-28T21:56:40","date_gmt":"2010-10-28T20:56:40","guid":{"rendered":"http:\/\/carnet.causeur.fr\/antidote\/?p=1046"},"modified":"2021-04-26T16:11:25","modified_gmt":"2021-04-26T14:11:25","slug":"harry-immergez-vous-dans-la-demographie","status":"publish","type":"post","link":"https:\/\/blog.causeur.fr\/antidote\/harry-immergez-vous-dans-la-demographie-1046","title":{"rendered":"Harry, immergez-vous dans la d\u00e9mographie !"},"content":{"rendered":"<p>Comme je ne regarde pas le journal de 20h en g\u00e9n\u00e9ral et celui de TF1 en particulier, je n&rsquo;aurais normalement pas avoir eu connaissance de la b\u00eatise dont Harry Roselmack a gratifi\u00e9 les t\u00e9l\u00e9spectateurs mercredi soir. Mais le zapping de Canal + m&rsquo;a rattrap\u00e9 et j&rsquo;ai donc pu entendre le pr\u00e9sentateur annoncer dans les titres :\u00a0\u00bbLa France championne d&rsquo;Europe du vieillissement\u00a0\u00bb.<\/p>\n<p>Ce titre \u00e9tait sens\u00e9 nous mettre en app\u00e9tit pour un reportage sur les centenaires qui devraient \u00eatre 200 000 en 2060. Pour autant, ce nombre de centenaires pr\u00e9vu\u00a0 fait-il de notre pays le champion d&rsquo;Europe du vieillissement de la population ? On conseille donc \u00e0 Harry Roselmack de s&rsquo;immerger -puisque, c&rsquo;est bien connu, l&rsquo;immersion, c&rsquo;est son truc- dans l&rsquo;\u00e9tude de la d\u00e9mographie europ\u00e9enne. Il apprendra alors que la natalit\u00e9 fran\u00e7aise se tire la bourre avec celle de l&rsquo;Irlande pour le titre de champion d&rsquo;Europe de la f\u00e9condit\u00e9. Et une recherche sur internet -qui m&rsquo;a pris une dizaine de minutes- permet de trouver le graphique suivant :<\/p>\n<p><a href=\"http:\/\/carnet.causeur.fr\/antidote\/?attachment_id=1048\" target=\"_blank\" rel=\"noopener\">Cliquer<\/a><\/p>\n<p>On le remarquera ais\u00e9ment, la France est loin du titre de champion d&rsquo;Europe du vieillissement \u00e0 l&rsquo;horizon cinquante ans.<\/p>\n<p>On me dira qu&rsquo;un pr\u00e9sentateur de journal ne peut pas \u00eatre sp\u00e9cialiste en tout. J&rsquo;en conviens. Mais alors pourquoi utiliser des termes aussi forts que \u00ab\u00a0championne d&rsquo;Europe du vieillissement\u00a0\u00bb ? Quand on ne sait pas, on s&rsquo;efforce de demeurer prudent. Enfin, la f\u00e9condit\u00e9 fran\u00e7aise a bien d\u00fb faire l&rsquo;objet de reportages de la premi\u00e8re cha\u00eene ces derni\u00e8res ann\u00e9es. Je ne suis pas certain, d&rsquo;ailleurs, qu&rsquo;on ne pourrait pas trouver une annonce du titre \u00ab\u00a0La France, championne d&rsquo;Europe de la natalit\u00e9\u00a0\u00bb dans la bouche du m\u00eame Roselmack ! Un peu de bon sens -qui sied \u00e0 tout professionnel- aurait pu emp\u00eacher le successeur de PPDA de se couvrir de ridicule.<\/p>\n<p>A moins que ce genre de slogan ne soit destin\u00e9 \u00e0 influencer le t\u00e9l\u00e9spectateur dans le d\u00e9bat sur les retraites. Est-ce-que quelqu&rsquo;un filmait M\u00e9lenchon en train de visionner cette s\u00e9quence ?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pour \u00e9viter de raconter des carabistouilles.<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":{"0":"post-1046","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-sulfate"},"_links":{"self":[{"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/posts\/1046","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/comments?post=1046"}],"version-history":[{"count":0,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/posts\/1046\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/media?parent=1046"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/categories?post=1046"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/tags?post=1046"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}