{"id":114,"date":"2007-06-23T20:56:53","date_gmt":"2007-06-23T19:56:53","guid":{"rendered":"http:\/\/carnet.causeur.fr\/antidote\/?p=114"},"modified":"2021-04-26T16:12:20","modified_gmt":"2021-04-26T14:12:20","slug":"traite-simplifie-ou-constitution-qui-ne-dit-pas-son-nom","status":"publish","type":"post","link":"https:\/\/blog.causeur.fr\/antidote\/traite-simplifie-ou-constitution-qui-ne-dit-pas-son-nom-114","title":{"rendered":"Trait\u00e9 simplifi\u00e9 ou Constitution qui ne dit pas son nom ?"},"content":{"rendered":"<p><!--[if gte mso 9]&amp;gt;  Normal 0 21       MicrosoftInternetExplorer4  &amp;lt;![endif]--><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify\"><span style=\"font-family: Verdana\">Cette nuit, les partenaires semblent avoir trouv\u00e9 un accord sur le trait\u00e9 simplifi\u00e9 qui devrait remplacer la Constitution europ\u00e9enne qui \u00e9tait morte depuis les r\u00e9f\u00e9rendums n\u00e9erlandais et fran\u00e7ais.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify\"><span style=\"font-family: Verdana\">Mais est-ce vraiment un simple trait\u00e9 de fonctionnement des institutions europ\u00e9ennes ou est-ce en fait une constitution europ\u00e9enne qui ne dit pas son nom ? Nous aurons la r\u00e9ponse lorsque nous pourrons savoir si l&rsquo;article I-6 qui figurait dans le texte que nous avons refus\u00e9 il y a deux ans trouve un \u00e9quivalent dans le nouveau projet. Cet article stipulait que le droit europ\u00e9en primait sur le droit des Etats membres et donc y compris sur leurs Constitutions nationales. Ne nous y trompons pas, c&rsquo;est cette disposition qui donnait au TCE le caract\u00e8re supranational, f\u00e9d\u00e9ral, aux institutions europ\u00e9ennes et qui lui donnait de facto la nature de Constitution.<\/span><\/p>\n<p class=\"MsoNormal\" style=\"text-align: justify\"><span style=\"font-family: Verdana\">Si une telle disposition figurait dans l&rsquo;accord trouv\u00e9 cette nuit, ne pas soumettre ce trait\u00e9\u00a0 au Peuple mais passer par le Congr\u00e8s serait une forfaiture. Les parlementaires qui d\u00e9poss\u00e8deraient ainsi la France de ce qui reste de sa Souverainet\u00e9 devraient en r\u00e9pondre devant l&rsquo;Histoire. Cette derni\u00e8re n&rsquo;est jamais tendre avec ceux qui, d&rsquo;Isabeau de Bavi\u00e8re au Mar\u00e9chal P\u00e9tain, se sont assis sur la Souverainet\u00e9 fran\u00e7aise<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cette nuit, les partenaires semblent avoir trouv\u00e9 un accord sur le trait\u00e9 simplifi\u00e9 qui devrait remplacer la Constitution europ\u00e9enne qui \u00e9tait morte depuis les r\u00e9f\u00e9rendums n\u00e9erlandais et fran\u00e7ais. Mais est-ce vraiment un simple trait\u00e9 de fonctionnement des institutions europ\u00e9ennes ou est-ce en fait une constitution europ\u00e9enne qui ne dit pas son nom ? Nous aurons [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":{"0":"post-114","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-oxygene"},"_links":{"self":[{"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/posts\/114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/comments?post=114"}],"version-history":[{"count":0,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/posts\/114\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/media?parent=114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/categories?post=114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/tags?post=114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}