{"id":2650,"date":"2013-01-02T10:50:42","date_gmt":"2013-01-02T10:50:42","guid":{"rendered":"http:\/\/blog.causeur.fr\/antidote\/?p=2650"},"modified":"2021-04-26T16:10:41","modified_gmt":"2021-04-26T14:10:41","slug":"ayrault-sest-il-mis-minable-en-decorant-tsonga","status":"publish","type":"post","link":"https:\/\/blog.causeur.fr\/antidote\/ayrault-sest-il-mis-minable-en-decorant-tsonga-2650","title":{"rendered":"Ayrault s\u2019est-il mis \u201cminable\u201d en d\u00e9corant Tsonga ?"},"content":{"rendered":"<p><a href=\"http:\/\/blog.causeur.fr\/antidote\/files\/2010\/05\/tsonga.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-full wp-image-646\" src=\"http:\/\/blog.causeur.fr\/antidote\/files\/2010\/05\/tsonga.jpg\" alt=\"\" width=\"159\" height=\"240\" \/><\/a><\/p>\n<p>La promotion des m\u00e9daill\u00e9s du 1er janvier de cette nouvelle ann\u00e9e nous a r\u00e9serv\u00e9 une jolie surprise. Ce n\u2019est pas l\u2019Ordre national de la L\u00e9gion d\u2019honneur qui a retenu notre attention mais celui, tout aussi national, du M\u00e9rite. On y a en effet d\u00e9couvert le tennisman Jo-Wilfried Tsonga, qui serait ainsi r\u00e9compens\u00e9 pour son autre m\u00e9daille, obtenue \u00e0 Londres l\u2019\u00e9t\u00e9 dernier aux Jeux Olympiques.<\/p>\n<p>Il semble \u00e9vident que cette promotion n\u2019ait pas \u00e9t\u00e9 vis\u00e9e \u00e0 Matignon. On ne peut en effet pas imaginer une seule seconde que Jean-Marc Ayrault, qui a fait de l\u2019\u00e9migration fiscale un cheval de bataille et avait, \u00e0 ce titre, interpell\u00e9 G\u00e9rard Depardieu et son<em>\u201ccomportement minable\u201d<\/em>, ne puisse accepter que Tsonga re\u00e7oive ainsi les honneurs de la R\u00e9publique. Car Tsonga n\u2019a pas attendu la fameuse taxe \u00e0 75% -laquelle, d\u2019ailleurs, n\u2019existe plus- pour prendre le chemin de la Suisse. Il l\u2019a fait aussit\u00f4t ses premiers gros gains sur le circuit international de la petite balle jaune ; ce qui ne l\u2019emp\u00eachait d\u2019ailleurs pas de donner, \u00e0 l\u2019occasion des le\u00e7ons de solidarit\u00e9 nationale \u00e0 la F\u00e9d\u00e9ration Fran\u00e7aise de Tennis comme nous l\u2019avions expliqu\u00e9\u00a0<a href=\"http:\/\/blog.causeur.fr\/antidote\/quand-lemigre-fiscal-donne-des-lecons-de-solidarite-nationale,00645\" target=\"_blank\" rel=\"noopener\">ici\u00a0<\/a>en mai 2010.<\/p>\n<p>On a beau avoir regrett\u00e9 aussi le d\u00e9part de Depardieu pour la Belgique, on ne peut que constater que, de son point de vue, l\u2019acteur a \u00e9t\u00e9 beaucoup plus patient que Tsonga. Ce dernier n\u2019est d\u2019ailleurs pas le seul tennisman fran\u00e7ais \u00e0 appr\u00e9cier les montagnes suisses au point d\u2019y fixer sa r\u00e9sidence. On renverra volontiers, \u00e0 cet \u00e9gard, \u00a0\u00e0 une<a href=\"http:\/\/actiondiscrete.tumblr.com\/post\/2504271820\/tennis-suisse\" target=\"_blank\" rel=\"noopener\">\u00a0\u00e9mission d\u2019Action discr\u00e8te<\/a>. En attendant, je vouerai reconnaissance \u00e9ternelle au premier journaliste qui interrogera le Premier Ministre :\u00a0<em>\u201cDans l\u2019\u00e9chelle du minable, comment situez-vous le comportement de Jo-Wilfried Tsonga, lequel sera pourtant d\u00e9cor\u00e9 par votre gouvernement, de l\u2019ordre national du m\u00e9rite ?\u201d<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La promotion des m\u00e9daill\u00e9s du 1er janvier de cette nouvelle ann\u00e9e nous a r\u00e9serv\u00e9 une jolie surprise. Ce n\u2019est pas l\u2019Ordre national de la L\u00e9gion d\u2019honneur qui a retenu notre attention mais celui, tout aussi national, du M\u00e9rite. On y a en effet d\u00e9couvert le tennisman Jo-Wilfried Tsonga, qui serait ainsi r\u00e9compens\u00e9 pour son autre [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":{"0":"post-2650","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-sulfate"},"_links":{"self":[{"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/posts\/2650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/comments?post=2650"}],"version-history":[{"count":0,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/posts\/2650\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/media?parent=2650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/categories?post=2650"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/tags?post=2650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}