{"id":304,"date":"2009-06-06T13:40:10","date_gmt":"2009-06-06T12:40:10","guid":{"rendered":"http:\/\/carnet.causeur.fr\/antidote\/?p=304"},"modified":"2021-04-26T16:12:03","modified_gmt":"2021-04-26T14:12:03","slug":"le-voile-librement-consenti-bientot-de-retour-dans-nos-ecoles","status":"publish","type":"post","link":"https:\/\/blog.causeur.fr\/antidote\/le-voile-librement-consenti-bientot-de-retour-dans-nos-ecoles-304","title":{"rendered":"Le voile &quot;librement consenti&quot; bient\u00f4t de retour dans nos \u00e9coles ?"},"content":{"rendered":"<p>Assistant au point-presse des deux pr\u00e9sidents, am\u00e9ricain et fran\u00e7ais, devant mon poste, j&rsquo;attendais avec impatience qu&rsquo;un journaliste les interroge sur la loi d&rsquo;interdiction des signes religieux \u00e0 l&rsquo;Ecole, faisant suite au discours de Barack Obama au Caire. C&rsquo;est Arnaud Parmentier, journaliste au Monde, qui s&rsquo;en est charg\u00e9.<\/p>\n<p><a href=\"http:\/\/www.causeur.fr\/american-hidjab,2521\" target=\"_blank\" rel=\"noopener\">Comme je l&rsquo;ai \u00e9crit hier<\/a>, la r\u00e9ponse du Pr\u00e9sident am\u00e9ricain m&rsquo;importait peu[1. A moins qu&rsquo;il n&rsquo;ait eu l&rsquo;intention de faire respecter son point de vue gr\u00e2ce \u00e0 la force des ba\u00efonnettes]. C&rsquo;est \u00e9videmment celle de Nicolas Sarkozy qui m&rsquo;int\u00e9ressait au vu des positions ant\u00e9rieures qu&rsquo;il avait port\u00e9es et que j&rsquo;ai expos\u00e9es hier, \u00e0 savoir son opposition farouche \u00e0 voir le Parlement l\u00e9gif\u00e9rer sur le sujet.<\/p>\n<p>Ayant \u00e9chou\u00e9 dans cette entreprise et observ\u00e9 que cette loi rencontrait un v\u00e9ritable succ\u00e8s en terme d&rsquo;efficacit\u00e9[2. On avait pu remarquer que sa campagne pr\u00e9sidentielle ne proposait pas d&rsquo;abroger cette loi contraire \u00e0 ses convictions mais tr\u00e8s populaire dans le pays], on pouvait l\u00e9gitimement attendre, en tant que citoyens, \u00e0 ce que le Pr\u00e9sident de la R\u00e9publique d\u00e9fende la Loi de celle-ci.<\/p>\n<p>Tel ne fut pas le cas puisque Nicolas Sarkozy a seulement assum\u00e9 l&rsquo;interdiction pour un fonctionnaire, au guichet de l&rsquo;administration, de porter un signe religieux ostensible. Pour le reste, il se disait en accord avec Barack Obama, qui venait de rappeler son attachement \u00e0 la totale libert\u00e9 d&rsquo;expression religieuse, \u00e0\u00a0 la condition, ajoutait-il, que le port du voile soit librement consenti et non le fruit de l&rsquo;environnement des jeunes filles. D&rsquo;interdiction dans les \u00e9coles, il ne fut donc pas question.<\/p>\n<p>D\u00e8s lors, on peut se poser une question bien l\u00e9gitime : Nicolas Sarkozy a t-il r\u00e9ellement l&rsquo;intention de mettre ses convictions, toujours intactes sur le sujet, dans la Loi et donc d&rsquo;abroger celle qu&rsquo;il combattait en 2004 ? Si c&rsquo;est le cas, on aurait pr\u00e9f\u00e9r\u00e9 qu&rsquo;il r\u00e9serv\u00e2t cette annonce aux Fran\u00e7ais, si possible avant les \u00e9lections pr\u00e9sidentielles, et pas dans une conf\u00e9rence de presse commune avec le Pr\u00e9sident des Etats-Unis. Si tel n&rsquo;est pas le cas, il vient de porter un grave coup \u00e0 l&rsquo;Autorit\u00e9 de la Loi. Qui va d\u00e9sormais emp\u00eacher des jeunes filles musulmanes de se pr\u00e9valoir des paroles pr\u00e9sidentielles en affirmant que c&rsquo;est avec leur total consentement qu&rsquo;elle viennent ainsi recouvertes sur les bancs de leurs \u00e9coles ?<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le Pr\u00e9sident de la R\u00e9publique fran\u00e7aise donne raison \u00e0 Barack Obama<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":{"0":"post-304","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-sulfate"},"_links":{"self":[{"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/posts\/304","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/comments?post=304"}],"version-history":[{"count":0,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/posts\/304\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/media?parent=304"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/categories?post=304"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/tags?post=304"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}