{"id":3274,"date":"2017-02-14T09:30:58","date_gmt":"2017-02-14T07:30:58","guid":{"rendered":"http:\/\/blog.causeur.fr\/antidote\/?p=3274"},"modified":"2021-04-26T16:10:10","modified_gmt":"2021-04-26T14:10:10","slug":"qui-peut-battre-marine-le-pen","status":"publish","type":"post","link":"https:\/\/blog.causeur.fr\/antidote\/qui-peut-battre-marine-le-pen-3274","title":{"rendered":"Qui peut battre Marine Le Pen?"},"content":{"rendered":"<h3>Personne, \u00e0 moins que \u2026<\/h3>\n<p><a href=\"http:\/\/blog.causeur.fr\/antidote\/files\/2015\/10\/marine-le-pen-besancon-1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignleft size-medium wp-image-3067\" src=\"http:\/\/blog.causeur.fr\/antidote\/files\/2015\/10\/marine-le-pen-besancon-1-300x182.jpg\" alt=\"\" width=\"300\" height=\"182\" srcset=\"https:\/\/blog.causeur.fr\/antidote\/wp-content\/uploads\/sites\/9\/2015\/10\/marine-le-pen-besancon-1-300x182.jpg 300w, https:\/\/blog.causeur.fr\/antidote\/wp-content\/uploads\/sites\/9\/2015\/10\/marine-le-pen-besancon-1.jpg 460w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"http:\/\/www.causeur.fr\/blog\/sujet\/marine-le-pen\">Marine Le Pen<\/a>\u00a0\u00e9tait attendue au tournant. D\u00e9sormais en t\u00eate de toutes les \u00e9tudes d\u2019opinion pour le premier tour de l\u2019\u00e9lection pr\u00e9sidentielle, sa participation \u00e0 la plus grande \u00e9mission politique de la t\u00e9l\u00e9vision fran\u00e7aise \u00e9tait assur\u00e9ment pour elle le rendez-vous \u00e0 ne pas manquer. De l\u2019avis g\u00e9n\u00e9ral, elle a r\u00e9ussi l\u2019exercice et domin\u00e9 tous ses interlocuteurs de la t\u00eate et des \u00e9paules. Seule\u00a0<a href=\"http:\/\/www.causeur.fr\/blog\/sujet\/najat-vallaud-belkacem\">Najat Vallaud-Belkacem<\/a>, \u00e0 la faveur d\u2019un expos\u00e9 liminaire de cinq minutes, a sembl\u00e9 pouvoir la mettre en difficult\u00e9 sur la question des \u00e9coles hors-contrats pourvoyeuse de fondamentalisme. Cinq petites minutes sur une \u00e9mission de deux heures, convenons que c\u2019est n\u00e9gligeable. <!--more-->Sur l\u2019\u00e9conomie, notamment, elle fait d\u00e9sormais mieux que tenir t\u00eate au sp\u00e9cialiste-maison, Fran\u00e7ois Lenglet. Ce dernier n\u2019a parfois pu qu\u2019opiner du chef devant la d\u00e9monstration de la candidate du FN. Il nous a sembl\u00e9 que cette derni\u00e8re s\u2019appuyait parfois sur les propres ouvrages de son interlocuteur, ce qui a d\u00fb participer \u00e0 cette domination. Il y a cinq ans, elle se montrait davantage en difficult\u00e9 face au m\u00eame journaliste. Qu\u2019a-t-il pu se passer entre les deux ? Sans doute a-t-elle mieux travaill\u00e9 le sujet, bien entendu. Mais l\u2019essentiel n\u2019est pas l\u00e0. Marine Le Pen a d\u00e9sormais le vent dans le dos, situation dont n\u2019importe quel cycliste du dimanche vous dira que cela comble le d\u00e9ficit d\u2019heures d\u2019entra\u00eenement. Depuis 2012, la crise grecque, le\u00a0<a href=\"http:\/\/www.causeur.fr\/blog\/sujet\/brexit\">Brexit\u00a0<\/a>et la campagne victorieuse de\u00a0<a href=\"http:\/\/www.causeur.fr\/blog\/sujet\/donald-trump\">Trump<\/a>\u00a0(dont l\u2019aspect \u00e9conomique a \u00e9t\u00e9 trop longtemps n\u00e9glig\u00e9 par la presse de ce c\u00f4t\u00e9-ci de l\u2019Atlantique) sont pass\u00e9s par l\u00e0. Libert\u00e9 mon\u00e9taire et protectionnisme sont beaucoup plus ais\u00e9s \u00e0 d\u00e9fendre. L\u2019\u00e9change avec l\u2019invit\u00e9 surprise\u00a0<a href=\"http:\/\/www.causeur.fr\/blog\/sujet\/patrick-buisson\">Patrick Buisson<\/a>\u00a0s\u2019est aussi pass\u00e9 au mieux pour la candidate. L\u2019ancien conseiller de\u00a0<a href=\"http:\/\/www.causeur.fr\/blog\/sujet\/nicolas-sarkozy\">Nicolas Sarkozy<\/a>\u00a0ne l\u2019a pas d\u00e9stabilis\u00e9e, lui reprochant parfois d\u2019\u00eatre trop \u00e0 droite (scolarisation des enfants \u00e9trangers), puis parfois de ne pas l\u2019\u00eatre assez. Mais \u00e9tait-ce vraiment l\u2019objectif de Patrick Buisson de la d\u00e9stabiliser ? Au bout de deux heures, le r\u00e9sultat du traditionnel sondage tombait : elle s\u2019\u00e9tait montr\u00e9e plus convaincante que tous ses concurrents aujourd\u2019hui en lice pour la pr\u00e9sidentielle, invit\u00e9s avant elle dans l\u2019\u00e9mission,\u00a0<a href=\"http:\/\/www.causeur.fr\/blog\/sujet\/francois-fillon\">Fran\u00e7ois Fillon\u00a0<\/a>et\u00a0<a href=\"http:\/\/www.causeur.fr\/blog\/sujet\/benoit-hamon\">Beno\u00eet Hamon<\/a>. Cette \u00e9mission s\u2019apparentait \u00e0 une v\u00e9ritable d\u00e9monstration de force.<\/p>\n<h3>Marine pr\u00e9sidente ?<\/h3>\n<p>D\u00e8s lors, le lendemain, beaucoup d\u2019observateurs se posaient LA question, \u00e0 juste titre : \u00ab peut-elle finalement gagner ? \u00bb. Et n\u2019y r\u00e9pondaient plus aussi facilement par la n\u00e9gative qu\u2019il y a quelques semaines encore. Ajoutons qu\u2019elle semble avoir impos\u00e9 une tr\u00eave entre<a href=\"http:\/\/www.causeur.fr\/blog\/sujet\/florian-philippot\">\u00a0Florian Philippot\u00a0<\/a>et\u00a0<a href=\"http:\/\/www.causeur.fr\/blog\/sujet\/marion-marechal-le-pen\">Marion Mar\u00e9chal-Le Pen<\/a>, dont les disputes \u00e0 ciel ouvert constituaient l\u2019obstacle le plus dangereux sur le chemin d\u2019une campagne \u00e9lectorale r\u00e9ussie. Nous savons qu\u2019il est imprudent de jouer au jeu des pronostics dans la campagne pr\u00e9sidentielle la plus incertaine de l\u2019histoire de la R\u00e9publique, mais mouillons-nous n\u00e9anmoins : comptes tenus des \u00e9tudes d\u2019opinions et des dynamiques de campagne, il est fort probable que Marine Le Pen vire en t\u00eate du premier tour le 23 avril prochain. Non seulement, elle est en t\u00eate de toutes les \u00e9tudes mais ces derni\u00e8res pr\u00e9cisent que la candidate du FN est dot\u00e9e du socle le plus solide de sond\u00e9s s\u00fbrs de leur vote : autour des 80% lorsqu\u2019<a href=\"http:\/\/www.causeur.fr\/blog\/sujet\/emmanuel-macron\/page\/2\">Emmanuel Macron<\/a>\u00a0et Beno\u00eet Hamon tournent plut\u00f4t autour des 40\/50%. Le socle de Fran\u00e7ois Fillon est interm\u00e9diaire. Son probl\u00e8me \u00e0 lui, c\u2019est que la dynamique est tellement d\u00e9sastreuse qu\u2019il ne lui restera peut-\u00eatre bient\u00f4t que ledit socle. Apr\u00e8s l\u2019effet d\u2019aubaine du lendemain de primaire d\u00e9but d\u00e9cembre (effet trompeur dont semble profiter aujourd\u2019hui Hamon), les sondages de Fran\u00e7ois Fillon avaient d\u00e9j\u00e0 enclench\u00e9 une baisse r\u00e9guli\u00e8re qui s\u2019est \u00e9videmment acc\u00e9l\u00e9r\u00e9e avec le d\u00e9clenchement des affaires concernant son \u00e9pouse et sa soci\u00e9t\u00e9 de conseil. On ne reviendra pas ici sur les affaires Fillon et leurs traitements judiciaire et m\u00e9diatique.\u00a0<em>Causeur<\/em>\u00a0y a d\u00e9j\u00e0 consacr\u00e9 bon nombre d\u2019articles. Mais d\u00e8s lors que le d\u00e9put\u00e9 de Paris avait r\u00e9ussi (provisoirement ?) \u00e0 tordre le cou \u00e0 autant de canards en forme de plans B, il n\u2019avait plus le choix que de s\u2019\u00e9riger en candidat anti-syst\u00e8me, en \u00ab Trump fran\u00e7ais \u00bb r\u00e9ussissant \u00e0 faire des attaques contre lui, une force. Il s\u2019y est essay\u00e9 depuis sa conf\u00e9rence de presse mais il y a un gros caillou dans la chaussure : le programme de Fran\u00e7ois Fillon n\u2019a rien de trumpiste. Il ressemble davantage \u00e0 celui de Madame\u00a0<a href=\"http:\/\/www.causeur.fr\/blog\/sujet\/angela-merkel\">Merkel<\/a>, qui est justement l\u2019une des critiques les plus farouches du nouveau pr\u00e9sident am\u00e9ricain, sur le fond comme sur la forme. Une \u00e9tude publi\u00e9e ce dimanche par le sondeur Yves-Marie Cann explique d\u2019ailleurs le d\u00e9ficit d\u2019audience structurel de Fran\u00e7ois Fillon dans les classes populaires : \u00ab\u00a0<em>Quant \u00e0 Fran\u00e7ois Fillon, pour conserver ses chances de qualification au second tour de l\u2019\u00e9lection pr\u00e9sidentielle, il lui faudra retrouver les faveurs des actifs, et plus particuli\u00e8rement des cat\u00e9gories populaires qui semblent avoir d\u00e9sert\u00e9 sa candidature. Au-del\u00e0 des accusations dont il fait l\u2019objet et dont on mesure ici les r\u00e9percussions, le programme \u201cradical\u201d du vainqueur de la primaire de la droite et du centre pourrait constituer un \u00e9cueil non n\u00e9gligeable, point qu\u2019ont d\u2019ailleurs soulev\u00e9 \u00e0 plusieurs reprises de certains membres de sa famille politique.<\/em>\u00bb.<\/p>\n<h3>Un autre candidat de la fronti\u00e8re ?<\/h3>\n<p>Emmanuel Macron pourrait bien vite \u00eatre frapp\u00e9 des m\u00eames faiblesses face \u00e0 Marine Le Pen. L\u2019ex-ministre de l\u2019\u00e9conomie a beau tenter lui aussi de se faire passer pour \u00ab anti-syst\u00e8me \u00bb, il n\u2019est qu\u2019\u00e0 voir la liste de ses soutiens s\u2019allonger pour se rendre compte de la supercherie. On comprend qu\u2019il tarde \u00e0 pr\u00e9senter son projet mais il faudra pourtant bien un jour retirer le masque : Emmanuel Macron est bien le candidat estampill\u00e9 \u00ab mondialisation heureuse \u00bb. Cela appara\u00eetrait d\u2019autant plus dans un second tour o\u00f9 il affronterait Marine Le Pen. Aujourd\u2019hui, les sondages annoncent une victoire 63\/37 pour le candidat\u00a0<em>En Marche<\/em>\u00a0dans cette hypoth\u00e8se. A vrai dire, il est improbable, dans le contexte des vents \u00e9voqu\u00e9s plus haut en faveur des candidats \u00ab\u00a0<em>de la protection, de la fronti\u00e8re<\/em>\u00a0\u00bb dans le monde occidental, on aboutisse \u00e0 une telle diff\u00e9rence au b\u00e9n\u00e9fice des candidats \u00ab<em>\u00a0de l\u2019ouverture, de la mondialisation<\/em>\u00a0\u00bb. L\u2019Histoire r\u00e9cente nous a au contraire montr\u00e9 que la tendance \u00e9tait inverse. En fait, il appara\u00eet de plus en plus que la seule mani\u00e8re de voir battu un \u00ab candidat de la fronti\u00e8re \u00bb serait de lui opposer un autre \u00ab candidat de la fronti\u00e8re \u00bb. Trump aurait-il vaincu\u00a0<a href=\"http:\/\/www.causeur.fr\/blog\/sujet\/bernie-sanders\">Bernie Sanders<\/a>\u00a0? Nul ne le saura jamais mais il est certain que les \u00ab swing states \u00bb de la Rust belt ont \u00e9t\u00e9 d\u00e9cisifs dans la victoire du nouveau pr\u00e9sident am\u00e9ricain et qu\u2019<a href=\"http:\/\/www.causeur.fr\/blog\/sujet\/hillary-clinton\">Hillary Clinton<\/a>\u00a0y \u00e9tait sans doute moins bien arm\u00e9e que son concurrent de la primaire d\u00e9mocrate. Qui pourrait \u00eatre alors ce \u00ab Sanders qui r\u00e9ussit \u00bb ? Certainement pas Beno\u00eet Hamon qui a d\u00e9j\u00e0 c\u00e9d\u00e9 face au capitalisme californien des GAFA en actant la fin du travail, \u00e0 travers la cr\u00e9ation d\u2019un revenu universel. Seul\u00a0<a href=\"http:\/\/www.causeur.fr\/blog\/sujet\/jean-luc-melenchon\">Jean-Luc M\u00e9lenchon<\/a>\u00a0pourrait \u00e9ventuellement jouer ce r\u00f4le. Certes, il semble aujourd\u2019hui distanc\u00e9 et Beno\u00eet Hamon tente de lui mettre la pression. Les quinze prochains jours seront d\u00e9cisifs. Si le candidat de la \u00ab\u00a0<em>France insoumise<\/em>\u00a0\u00bb parvient \u00e0 repasser devant celui du PS, un effet de vote utile pourra s\u2019enclencher \u00e0 partir du mois de mars. Il y aurait alors une probabilit\u00e9 pour qu\u2019il parvienne \u00e0 s\u2019asseoir sur le deuxi\u00e8me strapontin du second tour. Et alors, \u00e0 condition d\u2019enfermer dans une pi\u00e8ce\u00a0<a href=\"http:\/\/www.causeur.fr\/blog\/sujet\/clementine-autain\">Cl\u00e9mentine Autain<\/a>\u00a0et tous ses amis, et d\u2019en perdre la clef, Jean-Luc M\u00e9lenchon pourrait alors battre Marine Le Pen, au terme de la campagne la plus d\u00e9coiffante de la d\u00e9mocratie fran\u00e7aise.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Personne, \u00e0 moins que \u2026 Marine Le Pen\u00a0\u00e9tait attendue au tournant. D\u00e9sormais en t\u00eate de toutes les \u00e9tudes d\u2019opinion pour le premier tour de l\u2019\u00e9lection pr\u00e9sidentielle, sa participation \u00e0 la plus grande \u00e9mission politique de la t\u00e9l\u00e9vision fran\u00e7aise \u00e9tait assur\u00e9ment pour elle le rendez-vous \u00e0 ne pas manquer. De l\u2019avis g\u00e9n\u00e9ral, elle a r\u00e9ussi l\u2019exercice [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":{"0":"post-3274","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-oxygene"},"_links":{"self":[{"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/posts\/3274","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/comments?post=3274"}],"version-history":[{"count":0,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/posts\/3274\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/media?parent=3274"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/categories?post=3274"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/tags?post=3274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}