{"id":3299,"date":"2017-05-17T09:57:40","date_gmt":"2017-05-17T07:57:40","guid":{"rendered":"http:\/\/blog.causeur.fr\/antidote\/?p=3299"},"modified":"2021-04-26T16:09:59","modified_gmt":"2021-04-26T14:09:59","slug":"marine-le-pen-la-strategie-de-lechec","status":"publish","type":"post","link":"https:\/\/blog.causeur.fr\/antidote\/marine-le-pen-la-strategie-de-lechec-3299","title":{"rendered":"Marine Le Pen, la strat\u00e9gie de l\u2019\u00e9chec"},"content":{"rendered":"<h3>Les divisions du FN ne font que (re)commencer<\/h3>\n<p>Lib\u00e9ral, europ\u00e9iste et multiculturaliste, Emmanuel Macron tenait de l&rsquo;adversaire id\u00e9ale pour Marine Le Pen. C&rsquo;\u00e9tait sans compter sur les limites de la candidate frontiste, battue \u00e0 plates coutures hier soir.<\/p>\n<div><a href=\"http:\/\/blog.causeur.fr\/antidote\/?attachment_id=44225\" rel=\"attachment wp-att-44225\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/www.causeur.fr\/wp-content\/uploads\/2017\/05\/marine-le-pen-discours-presidentielle-660x400.jpg\" alt=\"\" width=\"660\" height=\"400\" \/><\/a>Marine Le Pen, Paris, 7 mai 2017. SIPA. AP22049727_000001<\/p>\n<\/div>\n<p>On aura beau dire que Marine Le Pen a doubl\u00e9 les voix de son p\u00e8re quinze ans plus t\u00f4t, son score est en-de\u00e7\u00e0 de ce qu\u2019elle pouvait esp\u00e9rer le 24 avril dernier. Apr\u00e8s avoir commenc\u00e9 la campagne de second tour sur les chapeaux de roue, Marine Le Pen a perdu la main \u00e0 mi-course. Alors que<a href=\"http:\/\/www.causeur.fr\/www.causeur.fr\/stephane-guillon-nicolas-dupont-aignan-44119.html\" target=\"_blank\" rel=\"noopener\">\u00a0le soutien de Nicolas Dupont-Aignan<\/a>\u00a0pouvait lui \u00eatre a priori profitable, elle a sign\u00e9 un accord laissant croire qu\u2019elle tergiversait sur la question mon\u00e9taire. Puis, incompr\u00e9hensiblement, elle a abord\u00e9 le face-\u00e0-face avec une agressivit\u00e9 et une hargne incompatibles avec la fonction pr\u00e9sidentielle, d\u00e9cevant jusqu\u2019\u00e0 certains de ses militants et \u00e9lecteurs.<\/p>\n<h3>D\u00e9ception en rase campagne<\/h3>\n<p>Apr\u00e8s six ans d\u2019efforts pour d\u00e9diaboliser son parti, elle a donn\u00e9 au pays l\u2019image exacte forg\u00e9e par ses adversaires. Nul doute que la posture de candidate ricaneuse a pes\u00e9 dans<a href=\"http:\/\/www.causeur.fr\/emmanuel-macron-president-republique-presidentielle-44216.html\" target=\"_blank\" rel=\"noopener\">\u00a0le score obtenu par Emmanuel Macron hier soir<\/a>\u00a0avec pr\u00e8s des deux-tiers des suffrages. Car l\u2019\u00e9chec de Marine Le Pen est l\u00e0\u00a0: alors que ce second tour se structurait sur le clivage qu\u2019elle souhaitait, par rapport \u00e0 la mondialisation et la construction europ\u00e9enne, alors que pr\u00e8s de la moiti\u00e9 des \u00e9lecteurs du premier tour avaient vot\u00e9 pour des candidats r\u00e9tifs \u00e0 la mondialisation heureuse, le candidate frontiste n\u2019en a finalement obtenu que le tiers.<\/p>\n<blockquote>\n<h3>&gt;&gt; A lire aussi:\u00a0<a href=\"http:\/\/www.causeur.fr\/emmanuel-macron-president-republique-presidentielle-44216.html\" target=\"_blank\" rel=\"noopener\">Youpi, la haine est finie! L\u2019\u00e9dito d\u2019Elisabeth L\u00e9vy<\/a><\/h3>\n<\/blockquote>\n<p>Le probl\u00e8me, c\u2019est donc elle et son parti. On nous r\u00e9torquera sans doute que les barrages construits autour d\u2019elle, le fameux cordon sanitaire politico-m\u00e9diatique en constituent la raison principale. Mais Marine Le Pen avait appris \u00e0 faire avec. Et le d\u00e9bat de mercredi devait justement permettre de cr\u00e9er des br\u00e8ches dans les fameux remparts. Au lieu de cela, elle les a sciemment renforc\u00e9s. D\u00e9sormais, la voil\u00e0 \u00e0 nouveau chef de guerre pour les l\u00e9gislatives. Sa d\u00e9faite constituera-t-elle un frein \u00e0 la mobilisation des \u00e9lecteurs ou profitera-t-elle au contraire du d\u00e9sordre chez Les R\u00e9publicains, \u00e9cartel\u00e9s entre ceux qui veulent d\u2019ores et d\u00e9j\u00e0 travailler avec le pr\u00e9sident \u00e9lu et les autres, men\u00e9s pas le p\u00e2le Fran\u00e7ois Baroin\u00a0? Assistera-t-on \u00e0 des remous au sein m\u00eame du FN alors qu\u2019elle a annonc\u00e9 d\u00e8s hier soir la cr\u00e9ation d\u2019un nouveau parti, en partenariat avec la formation de son nouvel alli\u00e9 Dupont-Aignan\u00a0?<\/p>\n<h3>Marion en embuscade?<\/h3>\n<p>Marion Mar\u00e9chal-Le Pen n\u2019a pas h\u00e9sit\u00e9 \u00e0 montrer\u00a0<a href=\"http:\/\/www.20minutes.fr\/elections\/2063615-20170507-video-resultat-presidentielle-marion-marechal-pen-fait-part-deception\" target=\"_blank\" rel=\"noopener\">sa d\u00e9ception<\/a>\u00a0et a regrett\u00e9 certains atermoiements, notamment sur l\u2019euro. On dit la d\u00e9put\u00e9e de Vaucluse h\u00e9sitante quant \u00e0 son avenir politique. Des rumeurs annon\u00e7aient m\u00eame qu\u2019<a href=\"http:\/\/www.lexpress.fr\/actualite\/politique\/elections\/bisbilles-au-fn-marion-marechal-le-pen-sur-le-depart_1896031.html\" target=\"_blank\" rel=\"noopener\">elle ne serait pas candidate \u00e0 sa succession<\/a>\u00a0dans sa circonscription\u00a0; sa pr\u00e9sence hier soir du c\u00f4t\u00e9 de Carpentras semble le d\u00e9mentir. Alors que Florian Philippot semble \u00e0 la fois affaibli par le score de Marine Le Pen et par l\u2019arriv\u00e9e dans le dispositif de Nicolas Dupont-Aignan qui le rend moins indispensable, Marion Mar\u00e9chal Le Pen a sans doute une carte \u00e0 jouer. Il n\u2019est d\u2019ailleurs pas impossible qu\u2019elle s\u2019entende mieux avec le leader de DLF que son rival Philippot. Le r\u00e9sultat des l\u00e9gislatives p\u00e8sera \u00e9norm\u00e9ment dans les \u00e9quilibres\u00a0; \u00e9lection ou non des principales personnalit\u00e9s, nombre de si\u00e8ges obtenus. Si Marion Mar\u00e9chal Le Pen parvenait par exemple \u00e0 prendre la t\u00eate d\u2019un groupe parlementaire dont sa tante serait absente, il pourrait y avoir de l\u2019\u00e9lectricit\u00e9 dans l\u2019air. Pas s\u00fbr d\u2019ailleurs, que cette hypoth\u00e8se contribuerait de mani\u00e8re plus efficace \u00e0 la d\u00e9diabolisation. Une nouvelle guerre des Le Pen pourrait bien avoir lieu. La saga familiale n\u2019est pas termin\u00e9e. Le nouveau pr\u00e9sident \u00e9lu ne s\u2019en plaindra pas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Les divisions du FN ne font que (re)commencer Lib\u00e9ral, europ\u00e9iste et multiculturaliste, Emmanuel Macron tenait de l&rsquo;adversaire id\u00e9ale pour Marine Le Pen. C&rsquo;\u00e9tait sans compter sur les limites de la candidate frontiste, battue \u00e0 plates coutures hier soir. Marine Le Pen, Paris, 7 mai 2017. SIPA. AP22049727_000001 On aura beau dire que Marine Le Pen [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":{"0":"post-3299","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-sulfate"},"_links":{"self":[{"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/posts\/3299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/comments?post=3299"}],"version-history":[{"count":0,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/posts\/3299\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/media?parent=3299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/categories?post=3299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/tags?post=3299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}