{"id":3361,"date":"2018-01-26T09:05:32","date_gmt":"2018-01-26T07:05:32","guid":{"rendered":"https:\/\/blog.causeur.fr\/antidote\/?p=3361"},"modified":"2021-04-26T16:09:58","modified_gmt":"2021-04-26T14:09:58","slug":"lemission-politique-wauquiez-dit-merci-a-ses-ennemis","status":"publish","type":"post","link":"https:\/\/blog.causeur.fr\/antidote\/lemission-politique-wauquiez-dit-merci-a-ses-ennemis-3361","title":{"rendered":"\u00ab L\u2019Emission politique \u00bb: Wauquiez dit merci \u00e0 ses ennemis"},"content":{"rendered":"<div class=\"td-pb-row\">\n<div class=\"td-pb-span12\">\n<div class=\"td-post-header\">\n<header class=\"td-post-title\">\n<div class=\"td-featured-image-rec\">\n<div class=\"td-post-featured-image\">\n<figure>\n<div class=\"td_block_wrap td_block_20 td_uid_18_5a6ab5ecb42cb_rand td-pb-border-top\">\n<div id=\"td_uid_18_5a6ab5ecb42cb\" class=\"td_block_inner td-column-2\">\n<div class=\"td_module_14 td_module_wrap td-animation-stack\">\n<div class=\"meta-info-container\">\n<div class=\"td-module-meta-info\">\n<div class=\"td-module-meta-holder\">\n<h3 class=\"td-excerpt\">Journalistes et invit\u00e9s lui ont rendu service en cherchant \u00e0 le tacler<\/h3>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"vc_row wpb_row vc_inner td-pb-row\"><\/div>\n<\/figure>\n<figure><a class=\"td-modal-image\" href=\"https:\/\/www.causeur.fr\/wp-content\/uploads\/2018\/01\/laurent-wauquiez-emission-politique-minc.png\"><img loading=\"lazy\" decoding=\"async\" class=\"entry-thumb\" title=\"laurent-wauquiez-emission-politique-minc\" src=\"https:\/\/www.causeur.fr\/wp-content\/uploads\/2018\/01\/laurent-wauquiez-emission-politique-minc.png\" alt=\"\" width=\"640\" height=\"389\" \/><\/a><figcaption class=\"wp-caption-text\"><\/figcaption><\/figure>\n<\/div>\n<\/div>\n<\/header>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"td-pb-row\">\n<div class=\"td-pb-span8 td-main-content\">\n<div class=\"td-ss-main-content\">\n<div id=\"content-hidden\">\n<div class=\"td-post-content\">\n<p>Laurent Wauquiez participait hier soir \u00e0 \u00ab\u00a0L\u2019Emission politique\u00a0\u00bb, son premier grand rendez-vous en tant que chef de parti. Entre ceux qui ont d\u00e9cid\u00e9 de claquer la porte et ceux qui ont d\u00e9cid\u00e9 de se tenir en r\u00e9serve, coinc\u00e9 entre le duo Macron-Philippe et un Front national (FN) qui cherche \u00e0 devenir plus euro-compatible, Laurent Wauquiez a n\u00e9anmoins acquis une l\u00e9gitimit\u00e9 dans les urnes, aupr\u00e8s des militants de son parti, et \u00e0 une large majorit\u00e9.<\/p>\n<h3>A la \u00ab\u00a0droite\u00a0\u00bb de la France\u00a0d\u2019en bas<\/h3>\n<p>D\u00e8s le d\u00e9but de l\u2019\u00e9mission, on a pu s\u2019apercevoir quelle \u00e9tait sa cible \u00e9lectorale\u00a0: la France p\u00e9riph\u00e9rique. Sa premi\u00e8re critique fut dirig\u00e9e contre l\u2019augmentation des taxes sur les carburants, d\u00e9cid\u00e9e par le gouvernement. Un bon d\u00e9but g\u00e2ch\u00e9 par cette manie de r\u00e9p\u00e9ter le mot \u00ab\u00a0droite\u00a0\u00bb toutes les deux phrases, comme pour conjurer le sort que les sondeurs lui promettent\u00a0: observer Emmanuel Macron devenir le nouveau leader de cette derni\u00e8re, r\u00e9alisant ce que RPR et UMP avaient promis \u00e0 cet \u00e9lectorat sans jamais vraiment le r\u00e9aliser. On ne parle pas \u00e0 la France p\u00e9riph\u00e9rique en se pla\u00e7ant dans un clivage dans laquelle elle ne croit plus depuis longtemps.<\/p>\n<div>\n<div>\n<div class=\"ak_placement_55225\">\n<div id=\"ak-b3aad7b3-1666-4b0a-a03b-fa1b5da2f9b5\">\n<div class=\"ak-content-desktop\">\n<div class=\"ak-container\">\n<div class=\"ak-cell ak-image ak-static\">\n<div class=\"ak-progress-bar\">\n<div>\n<div>\u00a0<strong>A lire aussi:\u00a0<a href=\"https:\/\/www.causeur.fr\/laurent-wauquiez-lr-republicains-droite-148185\" target=\"_blank\" rel=\"noopener\">Laurent Wauquiez: \u00ab\u00a0Quand la droite s\u2019assume, elle rayonne\u00a0\u00bb<\/a><\/strong><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>Cette France p\u00e9riph\u00e9rique, qui a majoritairement vot\u00e9 contre le trait\u00e9 de Maastricht en 1992 puis contre le TCE en 2005, s\u2019est trouv\u00e9e en difficult\u00e9 lorsque Fran\u00e7ois Lenglet lui a fait remarquer aussi malicieusement que pertinemment qu\u2019il \u00e9tait aussi illusoire de vouloir r\u00e9concilier Jean Monnet et\u00a0<a href=\"https:\/\/www.causeur.fr\/philippe-seguin-biographie-arnaud-teyssier-146924\" target=\"_blank\" rel=\"noopener\">Philippe S\u00e9guin<\/a>\u00a0sur l\u2019id\u00e9e europ\u00e9enne que de vouloir demeurer vierge et porter un enfant.<\/p>\n<h3>Garde tes ennemis pr\u00e8s de toi<\/h3>\n<p>C\u2019est la r\u00e9daction de\u00a0<em>France 2<\/em>\u00a0qui a livr\u00e9 le plus beau des cadeaux \u00e0 Laurent Wauquiez. Il ne manquait plus qu\u2019un joli ruban autour d\u2019Alain Minc, cet invit\u00e9 inattendu et id\u00e9al \u00e0 la fois. L\u2019ap\u00f4tre de la mondialisation a offert au pr\u00e9sident des R\u00e9publicains son meilleur passage de l\u2019\u00e9mission, le seul o\u00f9 il a oubli\u00e9 de sauter sur sa chaise comme un cabri en pronon\u00e7ant le mot \u00ab\u00a0droite\u00a0\u00bb. C\u2019est \u00e0 ce moment-l\u00e0 qu\u2019il a le mieux parl\u00e9 \u00e0 la France des provinces. Minc repr\u00e9sentait le projet macroniste en bien plus caricatural. Pendant cette dizaine de minutes, la nuance \u00e9tait du c\u00f4t\u00e9 de Wauquiez, et la caricature de celui du repr\u00e9sentant de la France des m\u00e9tropoles.<\/p>\n<p>La confrontation avec le porte-parole du gouvernement et putatif candidat LREM \u00e0 la mairie de Paris, Benjamin Griveaux, promettait donc de rendre un grand service \u00e0 celui qui reproche \u00e0 Emmanuel Macron d\u2019avoir la haine de la province. Benjamin Griveaux a commenc\u00e9 par lui faire remarquer, \u00e0 juste titre, que la question du clivage droite-gauche \u00e9tait d\u00e9su\u00e8te. Bon prince, il rendait service \u00e0 son interlocuteur qui lui rendait la pareille en lui faisant remarquer que pr\u00e8s de la moiti\u00e9 des baisses d\u2019imp\u00f4ts avaient profit\u00e9 aux 5% les plus riches. Jolie triangulation. C\u2019est l\u00e0 que Benjamin Griveaux a mis la question d\u2019Alstom sur la table, donnant l\u2019occasion \u00e0 Laurent Wauquiez de se montrer plus eurosceptique qu\u2019il ne l\u2019est vraiment. Le candidat macroniste de\u00a0<a href=\"https:\/\/www.causeur.fr\/nom-front-national-fn-changement-149112\" target=\"_blank\" rel=\"noopener\">la l\u00e9gislative partielle<\/a>\u00a0qui se d\u00e9roulera dimanche dans le Territoire de Belfort n\u2019a pas d\u00fb go\u00fbter le passage\u2026<\/p>\n<p>La journaliste Nathalie Saint-Cricq a conclu l\u2019\u00e9mission par la question de l\u2019identit\u00e9. Et permis au pr\u00e9sident LR de cocher la derni\u00e8re case ch\u00e8re \u00e0 la France p\u00e9riph\u00e9rique. Hier soir, les interlocuteurs de Laurent Wauquiez furent, de loin, ses meilleurs alli\u00e9s, lui permettant de se conforter dans sa strat\u00e9gie \u00e9lectorale. M\u00eame Fran\u00e7ois Lenglet, qui a point\u00e9 son angle mort europ\u00e9en, lui a rendu service\u00a0: c\u2019est maintenant cette question qu\u2019il doit trancher. Le sondage final (50% de convaincus) lui donne un peu de temps.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Journalistes et invit\u00e9s lui ont rendu service en cherchant \u00e0 le tacler Laurent Wauquiez participait hier soir \u00e0 \u00ab\u00a0L\u2019Emission politique\u00a0\u00bb, son premier grand rendez-vous en tant que chef de parti. Entre ceux qui ont d\u00e9cid\u00e9 de claquer la porte et ceux qui ont d\u00e9cid\u00e9 de se tenir en r\u00e9serve, coinc\u00e9 entre le duo Macron-Philippe et [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[],"class_list":{"0":"post-3361","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-oxygene"},"_links":{"self":[{"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/posts\/3361","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/comments?post=3361"}],"version-history":[{"count":0,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/posts\/3361\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/media?parent=3361"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/categories?post=3361"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/tags?post=3361"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}