{"id":3402,"date":"2018-11-16T17:54:12","date_gmt":"2018-11-16T15:54:12","guid":{"rendered":"https:\/\/blog.causeur.fr\/antidote\/?p=3402"},"modified":"2021-04-26T16:09:57","modified_gmt":"2021-04-26T14:09:57","slug":"le-pays-legal-doit-rencontrer-le-pays-reel-comme-la-dit-charles-macron","status":"publish","type":"post","link":"https:\/\/blog.causeur.fr\/antidote\/le-pays-legal-doit-rencontrer-le-pays-reel-comme-la-dit-charles-macron-3402","title":{"rendered":"Le pays l\u00e9gal doit rencontrer le pays r\u00e9el (comme l\u2019a dit Charles Macron)"},"content":{"rendered":"<h3 class=\"td-post-sub-title\">Le mea culpa du pr\u00e9sident n&rsquo;est-il qu&rsquo;un autre coup de com&rsquo; ?<\/h3>\n<div class=\"td-pb-row\">\n<div class=\"td-pb-span12\">\n<div class=\"td-post-header\">\n<header class=\"td-post-title\">\n<div class=\"td-featured-image-rec\">\n<div class=\"td-post-featured-image\">\n<figure><a class=\"td-modal-image\" href=\"https:\/\/www.causeur.fr\/wp-content\/uploads\/2018\/11\/macron-pays-legal-reel-mea-culpa.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"entry-thumb\" title=\"macron-pays-legal-reel-mea-culpa\" src=\"https:\/\/www.causeur.fr\/wp-content\/uploads\/2018\/11\/macron-pays-legal-reel-mea-culpa-1200x729.jpg\" alt=\"\" width=\"640\" height=\"389\" \/><\/a><figcaption class=\"wp-caption-text\"><\/figcaption><\/figure>\n<\/div>\n<\/div>\n<\/header>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"td-pb-row\">\n<div class=\"td-pb-span8 td-main-content\">\n<div class=\"td-ss-main-content\">\n<div id=\"content-hidden\">\n<div class=\"td-post-content\">\n<hr \/>\n<h3><strong>Sur le porte-avion Charles-de-Gaulle, Emmanuel Macron a fait son mea culpa: il n\u2019a\u00a0<em>\u00ab\u00a0pas r\u00e9ussi \u00e0 r\u00e9concilier le peuple fran\u00e7ais avec ses dirigeants\u00a0\u00bb<\/em>. R\u00e9elle prise de conscience ou \u00e9ni\u00e8me coup de com\u2019 ?<\/strong><\/h3>\n<hr \/>\n<p>\u00ab\u00a0L\u2019itin\u00e9rance m\u00e9morielle\u00a0\u00bb aurait-elle \u00e9t\u00e9 utile\u00a0? On penchait davantage pour le non \u00e0 la fin de la semaine derni\u00e8re. Voir chaque jour le pr\u00e9sident de la R\u00e9publique se faire houspiller, le voir ramer face \u00e0 des interlocuteurs qui ne d\u00e9sarmaient pas. O\u00f9 \u00e9tait pass\u00e9 la pr\u00e9sidence jupit\u00e9rienne\u00a0? Nous avions th\u00e9oris\u00e9 son abandon par le locataire de l\u2019Elys\u00e9e \u00e0 la fin de l\u2019\u00e9t\u00e9, mais pourquoi diable donner encore en spectacle ce renoncement en offrant l\u2019image du pr\u00e9sident qui se fait engueuler\u00a0?<\/p>\n<div><\/div>\n<h3><strong>Macron vient nous chercher\u2026<\/strong><\/h3>\n<p>Et puis mercredi soir, dans la derni\u00e8re partie de son entretien sur TF1 en direct du porte-avion Charles-de-Gaulle, Emmanuel Macron semblait transport\u00e9 par un \u00e9clair de lucidit\u00e9. Il t\u00e9moignait ainsi de son constat du divorce entre\u00a0<em>\u00ab\u00a0la base et le sommet\u00a0\u00bb,<\/em>\u00a0et constatait publiquement son \u00e9chec en mati\u00e8re de r\u00e9conciliation entre le peuple et ses classes dirigeantes. Il d\u00e9couvrait alors que les Fran\u00e7ais avaient besoin\u00a0<em>\u00ab\u00a0d\u2019\u00eatre consid\u00e9r\u00e9s, prot\u00e9g\u00e9s, et qu\u2019on leur apporte des solutions, pas seulement des d\u00e9clarations\u00a0\u00bb<\/em>.<\/p>\n<p>A trois jours de l\u2019op\u00e9ration des \u00ab\u00a0gilets jaunes\u00a0\u00bb, il \u00e9tait temps que le chef de l\u2019Etat le comprenne. Il \u00e9tait temps que l\u2019humilit\u00e9 remplace enfin l\u2019arrogance. On a encore en m\u00e9moire ses propos m\u00e9prisants tenus il y a un an dans la Creuse, o\u00f9 il d\u00e9non\u00e7ait ceux qui\u00a0<em>\u00ab\u00a0foutent le bordel\u00a0\u00bb,<\/em>\u00a0les enjoignant \u00e0 aller bosser \u00e0 deux heures de route \u2013 \u00e0 l\u2019\u00e9poque le prix du diesel n\u2019\u00e9tait pas aussi haut qu\u2019aujourd\u2019hui. On se souvient des d\u00e9clarations sur le\u00a0<em>\u00ab\u00a0pognon de dingue\u00a0\u00bb<\/em>\u00a0ou le surr\u00e9aliste\u00a0<em>\u00ab\u00a0qu\u2019ils viennent me chercher\u00a0\u00bb<\/em>\u00a0lanc\u00e9 \u00e0 son clan au plus fort de l\u2019affaire Benalla. On se rappelle enfin l\u2019obsession pr\u00e9sidentielle, sans cesse affirm\u00e9e, entre\u00a0<em>\u00ab\u00a0les progressistes et les nationalistes\u00a0\u00bb<\/em>, ce clivage qui renvoyait ainsi quiconque n\u2019adh\u00e9rant pas \u00e0 la marche du progr\u00e8s macronien aux heures les plus sombres de notre histoire. La soif de consid\u00e9ration, incontestablement, n\u2019avait pas \u00e9t\u00e9 \u00e9tanch\u00e9e apr\u00e8s cette succession d\u2019\u00e9pisodes.<\/p>\n<h3><strong>\u2026mais nous parle comme \u00e0 des gosses<\/strong><\/h3>\n<p>Mais il ne suffit pas de faire ce constat au pied d\u2019un Rafale. Il ne suffit pas que la presse unanime titre le lendemain sur le \u00ab\u00a0mea culpa du pr\u00e9sident\u00a0\u00bb. Il ne suffit pas non plus de promettre qu\u2019on reviendra au contact des Fran\u00e7ais, sans doute pour se faire engueuler une semaine de plus. Il faut d\u2019abord en tirer toutes les cons\u00e9quences. D\u2019abord en cessant d\u2019opposer les partisans du Progr\u00e8s \u00e0 la l\u00e8pre nationaliste, bien s\u00fbr. Mais il faut aller plus loin. Car ce qui agace, ce qui \u00e9nerve, ce qui met en col\u00e8re, c\u2019est aussi la fameuse antienne selon laquelle il faudrait faire preuve\u00a0<em>\u00ab\u00a0de p\u00e9dagogie\u00a0\u00bb<\/em>. Emmanuel Macron n\u2019est pas le premier \u00e0 tomber dans ce panneau, mais il en a constitu\u00e9 la caricature la plus aboutie, y compris mercredi soir dans la premi\u00e8re partie de son entretien.<\/p>\n<blockquote class=\"td_quote_box td_box_center\"><p><strong>A lire aussi:\u00a0<a href=\"https:\/\/www.causeur.fr\/macron-enfants-republique-saint-martin-155531\" target=\"_blank\" rel=\"noopener\">Papa Macron et les \u00ab\u00a0enfants\u00a0\u00bb de la R\u00e9publique<\/a><\/strong><\/p><\/blockquote>\n<p>La\u00a0<em>\u00ab\u00a0p\u00e9dagogie de la r\u00e9forme\u00a0\u00bb,<\/em>\u00a0ce\u00a0<em>\u00ab\u00a0je vais vous expliquer\u00a0\u00bb<\/em>\u00a0qu\u2019il a balanc\u00e9 \u00e0 ceux qui l\u2019interpellaient constitue en fait le summum de ce qui provoque le divorce entre ce que le pr\u00e9sident appelle\u00a0<em>\u00ab\u00a0 la base et le sommet\u00a0\u00bb<\/em>. Car la plupart du temps, ses interlocuteurs avaient tr\u00e8s bien compris\u00a0; simplement, ils n\u2019\u00e9taient pas d\u2019accord. Et pour le dire cr\u00fbment, cette persistance \u00e0\u00a0<em>\u00ab\u00a0expliquer\u00a0\u00bb<\/em>, \u00e0 afficher\u00a0<em>\u00ab\u00a0sa p\u00e9dagogie\u00a0\u00bb<\/em>\u00a0fait comprendre aux destinataires qu\u2019ils sont un peu dur de la feuille, ce qui n\u2019est gu\u00e8re agr\u00e9able. Ce constat vaut autant pour le pr\u00e9sident que pour ses ministres, dont certains tentent d\u2019expliquer aux propri\u00e9taires de v\u00e9hicules diesel \u2013 parfois acquis avec un bonus \u00e9cologique \u2013 qu\u2019il est tr\u00e8s r\u00e9pr\u00e9hensible de polluer l\u2019atmosph\u00e8re et d\u2019empoisonner ainsi leurs enfants. Il vaut aussi pour certains donneurs de le\u00e7ons qui s\u00e9vissent sur les plateaux de t\u00e9l\u00e9vision. On a ainsi pu entendre le directeur de\u00a0<em>Lib\u00e9ration<\/em>\u00a0tenter de conseiller aux ruraux de prendre le car et les r\u00e9primander quand ils vont acheter du pain avec leur automobile. Quand la premi\u00e8re boulangerie est \u00e0 cinq kilom\u00e8tres, on y va en trottinette\u00a0? Un autre, alors qu\u2019on lui faisait remarquer que les voitures \u00e9lectriques n\u2019\u00e9taient gu\u00e8re spacieuses, r\u00e9pondait que les grosses bagnoles, c\u2019\u00e9tait d\u00e9sormais ringard. Et les gosses\u00a0? On en fait quoi\u00a0? On les abandonne sur l\u2019autoroute\u00a0?<\/p>\n<h3><strong>Vivement samedi ?<\/strong><\/h3>\n<p>Le rendez-vous de samedi constitue un \u00e9v\u00e9nement \u00e0 haut-risque. Les \u00ab\u00a0gilets jaunes\u00a0\u00bb ont \u00e9t\u00e9 chauff\u00e9s \u00e0 blanc pendant des semaines et ce n\u2019est pas le mea culpa conc\u00e9d\u00e9 sur le Charles-de-Gaulle qui a frein\u00e9 leur d\u00e9termination. Les menaces de Christophe Castaner ou de Fran\u00e7ois de Rugy n\u2019ont pas d\u00fb calmer davantage leurs ardeurs. Les \u00ab\u00a0gilets jaunes\u00a0\u00bb n\u2019ont jamais eu l\u2019intention de bloquer les pompiers ni les ambulances. Leur faire ce proc\u00e8s d\u2019intention et pr\u00e9voir une confrontation avec eux ce week-end n\u2019entrerait pas en coh\u00e9rence avec l\u2019acc\u00e8s d\u2019humilit\u00e9 per\u00e7u mercredi soir. Le pr\u00e9sident a tout int\u00e9r\u00eat \u00e0 calmer le jeu. Comme on peut d\u00e9j\u00e0 le lire sur les r\u00e9seaux sociaux, il serait difficilement admis qu\u2019on r\u00e9prime les blocages \u00e0 des ronds-points alors qu\u2019on donne par ailleurs des ordres pour ne pas\u00a0<em>\u00ab\u00a0provoquer\u00a0\u00bb<\/em>\u00a0certains quartiers en faisant cesser les rod\u00e9os automobiles dont ils sont habituellement le th\u00e9\u00e2tre.<\/p>\n<p>Le mea culpa d\u2019Emmanuel Macron n\u2019est-il qu\u2019un coup de com\u2019 ou constitue-t-il v\u00e9ritablement une prise de conscience avec r\u00e9solutions coh\u00e9rentes \u00e0 l\u2019appui\u00a0? La mani\u00e8re dont il g\u00e8rera ce 17 novembre devrait nous donner un d\u00e9but de r\u00e9ponse.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Le mea culpa du pr\u00e9sident n&rsquo;est-il qu&rsquo;un autre coup de com&rsquo; ? Sur le porte-avion Charles-de-Gaulle, Emmanuel Macron a fait son mea culpa: il n\u2019a\u00a0\u00ab\u00a0pas r\u00e9ussi \u00e0 r\u00e9concilier le peuple fran\u00e7ais avec ses dirigeants\u00a0\u00bb. R\u00e9elle prise de conscience ou \u00e9ni\u00e8me coup de com\u2019 ? \u00ab\u00a0L\u2019itin\u00e9rance m\u00e9morielle\u00a0\u00bb aurait-elle \u00e9t\u00e9 utile\u00a0? On penchait davantage pour le non [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-3402","post","type-post","status-publish","format-standard","hentry","category-sulfate"],"_links":{"self":[{"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/posts\/3402","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/comments?post=3402"}],"version-history":[{"count":0,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/posts\/3402\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/media?parent=3402"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/categories?post=3402"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/tags?post=3402"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}