{"id":3469,"date":"2020-04-03T17:46:09","date_gmt":"2020-04-03T15:46:09","guid":{"rendered":"https:\/\/blog.causeur.fr\/antidote\/?p=3469"},"modified":"2021-04-26T16:09:56","modified_gmt":"2021-04-26T14:09:56","slug":"echange-geo-tracking-contre-autorisation-de-sortie","status":"publish","type":"post","link":"https:\/\/blog.causeur.fr\/antidote\/echange-geo-tracking-contre-autorisation-de-sortie-3469","title":{"rendered":"\u00c9change \u00ab g\u00e9o-tracking \u00bb contre autorisation de sortie"},"content":{"rendered":"<div class=\"td-pb-row\">\n<div class=\"td-pb-span12\">\n<div class=\"td-post-header\">\n<header class=\"td-post-title\">\n<div class=\"td-featured-image-rec\">\n<div class=\"td-post-featured-image\">\n<figure><a class=\"td-modal-image\" href=\"https:\/\/www.causeur.fr\/wp-content\/uploads\/2020\/04\/google-maps-geolocalisation-coronavirus.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"entry-thumb\" title=\"google-maps-geolocalisation-coronavirus\" src=\"https:\/\/www.causeur.fr\/wp-content\/uploads\/2020\/04\/google-maps-geolocalisation-coronavirus-1200x728.jpg\" alt=\"\" width=\"640\" height=\"388\" \/><\/a><figcaption class=\"wp-caption-text\"><\/figcaption><\/figure>\n<\/div>\n<\/div>\n<\/header>\n<\/div>\n<\/div>\n<\/div>\n<div class=\"td-pb-row\">\n<div class=\"td-pb-span8 td-main-content\">\n<div class=\"td-ss-main-content\">\n<div id=\"content-hidden\">\n<div class=\"td-post-content\">\n<hr \/>\n<h3><strong>Les Fran\u00e7ais sont-ils pr\u00eats \u00e0 accepter la g\u00e9olocalisation pour que le gouvernement desserre leur confinement drastique ?<\/strong><\/h3>\n<hr \/>\n<p>Geo-tracking. Cet anglicisme est \u00e0 la mode depuis quelques jours. Alors que nous sommes la plupart d\u2019entre nous assign\u00e9s \u00e0 r\u00e9sidence dans les pays occidentaux, ceux qu\u2019on appelait autrefois les Dragons d\u2019Asie impressionnent par leur ma\u00eetrise de l\u2019\u00e9pid\u00e9mie de Covid-19. Parmi les outils utilis\u00e9s notamment par la Cor\u00e9e du Sud, Taiwan et Singapour, figurent une v\u00e9ritable ma\u00eetrise de leurs fronti\u00e8res, l\u2019utilisation massive de tests et de masques, et enfin ce g\u00e9o-tracking. Il permet aux autorit\u00e9s gouvernementales de suivre \u00e0 la trace les porteurs du virus, gr\u00e2ce \u00e0 leur t\u00e9l\u00e9phone portable, de conna\u00eetre ceux qu\u2019ils auraient pu rencontrer et donc contaminer. Et de pouvoir <i>in fine<\/i>, \u00e9viter de telles rencontres en confinant tous ceux qu\u2019on a d\u00e9tect\u00e9s comme porteurs, et seulement ceux-l\u00e0.<\/p>\n<h3><b>Le d\u00e9confinement sera un long chemin de croix<\/b><\/h3>\n<p>Chez nous, la ma\u00eetrise des fronti\u00e8res est assimil\u00e9e aux \u00ab\u00a0heures sombres\u00a0\u00bb et, mis \u00e0 part l\u2019Allemagne, on a tr\u00e8s peu test\u00e9, car on n\u2019avait pas beaucoup de tests. Quant aux masques, on nous a d\u2019abord expliqu\u00e9 qu\u2019ils \u00e9taient inutiles au commun des mortels. Nous n\u2019\u00e9tions pas foutus de le mettre sur notre visage correctement. Maintenant, on nous incite \u00e0 fabriquer chacun le n\u00f4tre gr\u00e2ce \u00e0 des tutos sur internet. Et les \u00c9tats occidentaux se livrent \u00e0 une guerre impitoyable et plut\u00f4t path\u00e9tique, en interceptant des commandes destin\u00e9es \u00e0 d\u2019autres sur les tarmacs d\u00e9serts de leurs a\u00e9roports.<\/p>\n<blockquote class=\"td_quote_box td_box_center\"><p><strong>A lire aussi:\u00a0<a href=\"https:\/\/www.causeur.fr\/intelligence-artificielle-coronavirus-174871\" target=\"_blank\" rel=\"noopener\">L\u2019 IA assign\u00e9e \u00e0 r\u00e9sidence<\/a><\/strong><\/p><\/blockquote>\n<p>S\u2019agissant des fronti\u00e8res, tout de monde comprend d\u00e9sormais qu\u2019un d\u00e9confinement ne pourra s\u2019accompagner que d\u2019un contr\u00f4le drastique pour \u00e9viter l\u2019entr\u00e9e de porteurs du virus venant de pays qui ont choisi une autre politique (Pays-Bas ou Su\u00e8de, par exemple) que la n\u00f4tre. Notre gouvernement travaille \u00e9galement sur des tests les plus fiables possibles, notamment en s\u00e9rologie, permettant de savoir qui est immunis\u00e9, qui est porteur, et qui est aucun des deux.<\/p>\n<h3><b>Fran\u00e7ois Sureau nous met en garde<\/b><\/h3>\n<p>Reste donc le g\u00e9o-tracking, dont on a dit avec pertinence qu\u2019il ne correspond gu\u00e8re aux valeurs occidentales. La vie priv\u00e9e est consid\u00e9r\u00e9e chez nous comme un tr\u00e9sor, plus encore dans les pays latins, comme l\u2019a montr\u00e9 encore il y a quelques semaines \u2013 m\u00eame si \u00e7a nous para\u00eet un si\u00e8cle \u2013 la path\u00e9tique affaire Griveaux. L\u2019id\u00e9e que nous soyons ainsi g\u00e9o-localisables par les autorit\u00e9s, voire sur un site internet public, si on est contamin\u00e9 par un virus, ne nous est pas famili\u00e8re, loin s\u2019en faut. Les amateurs de vaudeville pourraient certes s\u2019en d\u00e9lecter\u00a0: imaginons que la mar\u00e9chauss\u00e9e d\u00e9barque chez vous au petit matin et explique devant conjoint et enfants que la personne avec laquelle vous avez pass\u00e9 l\u2019apr\u00e8s-midi deux jours plus t\u00f4t \u00e0 l\u2019H\u00f4tel de la gare \u00e9tait porteuse du Covid-19. On dit d\u2019ailleurs que beaucoup de couples n\u2019ont pas surv\u00e9cu \u00e0 ce genre de quiproquos du c\u00f4t\u00e9 de S\u00e9oul. La crainte est l\u00e9gitime que de telles dispositions adopt\u00e9es pendant cet \u00e9tat d\u2019urgence sanitaire deviennent ensuite d\u00e9finitives dans la loi. Fran\u00e7ois Sureau n\u2019a pas tort de nous mettre en garde sur notre propension collective \u00e0 abandonner nos libert\u00e9s fondamentales au profit de la s\u00e9curit\u00e9, en mati\u00e8re de lutte contre le terrorisme ou en mati\u00e8re sanitaire.<\/p>\n<p>Pour autant, Eric Zemmour a-t-il tort quand il explique que le confinement actuel est une des plus grandes atteintes aux libert\u00e9s fondamentales que nous ayons v\u00e9cu depuis bien longtemps\u00a0? Soyons honn\u00eates. J\u2019\u00e9changerais bien mon tra\u00e7age contre une randonn\u00e9e en for\u00eat, cette g\u00e9olocalisation permettant de garantir aux autorit\u00e9s que je ne rencontre personne. En \u00e9crivant cette derni\u00e8re phrase, je me rends compte du c\u00f4t\u00e9 flippant de la situation. Et pourtant, en y r\u00e9fl\u00e9chissant bien, je suis d\u00e9j\u00e0 trac\u00e9 quand je pars en rando. Car j\u2019utilise mon GPS et Monsieur Google sait \u00e0 tout moment o\u00f9 je suis.\u00a0 Pourquoi ferais-je davantage confiance \u00e0 ce dernier qu\u2019\u00e0 un \u00c9tat dont j\u2019\u00e9lis r\u00e9guli\u00e8rement les repr\u00e9sentants\u00a0? Quant \u00e0 Facebook, qu\u2019on me laisse t\u00e9moigner une anecdote. L\u2019autre jour, ma prog\u00e9niture dansait devant un jeu vid\u00e9o s\u2019intitulant \u00ab\u00a0Just Dance\u00a0\u00bb. J\u2019\u00e9tais \u00e0 quelques m\u00e8tres en train de surfer avec mon t\u00e9l\u00e9phone portable sur le r\u00e9seau social cr\u00e9\u00e9 par Zuckerberg. Et que croyez-vous qu\u2019il arriva\u00a0? Alors que la t\u00e9l\u00e9vision et le jeu vid\u00e9o ne sont nullement connect\u00e9s sur internet chez moi, Facebook m\u2019a propos\u00e9 quelques heures plus tard des publicit\u00e9s sponsoris\u00e9es pour la nouvelle version de \u00ab\u00a0Just Dance\u00a0\u00bb. Ce qui signifie tr\u00e8s clairement que Facebook a per\u00e7u \u2013 gr\u00e2ce au son \u2013 que le jeu int\u00e9ressait mon foyer. Ce qui signifie encore plus clairement, \u00e0 moins que je ne verse dans la parano\u00efa, que Facebook nous \u00e9coute, comme nous ne l\u2019accepterions pas de notre gouvernement, surtout si nous avons vu un jour \u201cLa vie des autres\u201d.<\/p>\n<h3><b>Les Fran\u00e7ais sont m\u00fbrs<\/b><\/h3>\n<p>Edouard Philippe a expliqu\u00e9 mercredi devant la mission parlementaire que le g\u00e9o-tracking ne pourrait \u00eatre utilis\u00e9 dans notre pays, compte tenu de nos traditions rappel\u00e9es plus haut, que sur la base du volontariat. Loin de moi l\u2019id\u00e9e de taxer Edouard Philippe d\u2019un cynisme qui consisterait \u00e0 privil\u00e9gier l\u2019id\u00e9e que nous sommes collectivement m\u00fbrs pour accepter volontairement ce tra\u00e7age. Il \u00e9tait sans doute sinc\u00e8re dans son souci de se montrer jaloux de nos libert\u00e9s fondamentales. Il n\u2019en reste pas moins que nous sommes sans doute collectivement m\u00fbrs, malgr\u00e9 tout.<\/p>\n<blockquote class=\"td_quote_box td_box_center\"><p><strong>A lire aussi:\u00a0<a href=\"https:\/\/www.causeur.fr\/coronavirus-italie-chine-coree-confinement-174036\" target=\"_blank\" rel=\"noopener\">Coronavirus: la Cor\u00e9e parvient \u00e0 endiguer l\u2019\u00e9pid\u00e9mie sans confinement<\/a><br \/>\n<\/strong><\/p><\/blockquote>\n<p>M\u00eame si je m\u2019inclus dans ce collectif ainsi conditionn\u00e9, par mes usages num\u00e9riques quotidiens, cette situation m\u2019inqui\u00e8te. Si un d\u00e9bat doit avoir lieu pendant l\u2019\u00e9tat d\u2019urgence sur cet outil de g\u00e9o-tracking, il devra imp\u00e9rativement faire l\u2019objet d\u2019une plus grande r\u00e9flexion quand nous aurons \u00e9limin\u00e9 Covid-19. Nos soci\u00e9t\u00e9s doivent vraiment se poser la question de notre souverainet\u00e9, collective et individuelle face aux GAFA. Nous devons imp\u00e9rativement nous interroger collectivement et individuellement sur notre consentement \u00e0 la surveillance.<\/p>\n<p>\u00ab\u00a0Le jour d\u2019apr\u00e8s ne sera pas comme le jour d\u2019avant\u00a0\u00bb, explique Emmanuel Macron. \u00c0 propos d\u2019une certaine id\u00e9e des fronti\u00e8res, de la mondialisation, de la souverainet\u00e9, c\u2019est vrai. Mais il faudra aussi ajouter la th\u00e9matique de la surveillance num\u00e9rique. Nous avons \u00e0 l\u2019\u00e9vidence d\u00e9j\u00e0 trop consenti.<\/p>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Les Fran\u00e7ais sont-ils pr\u00eats \u00e0 accepter la g\u00e9olocalisation pour que le gouvernement desserre leur confinement drastique ? Geo-tracking. Cet anglicisme est \u00e0 la mode depuis quelques jours. Alors que nous sommes la plupart d\u2019entre nous assign\u00e9s \u00e0 r\u00e9sidence dans les pays occidentaux, ceux qu\u2019on appelait autrefois les Dragons d\u2019Asie impressionnent par leur ma\u00eetrise de l\u2019\u00e9pid\u00e9mie [&hellip;]<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":{"0":"post-3469","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-sulfate"},"_links":{"self":[{"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/posts\/3469","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/comments?post=3469"}],"version-history":[{"count":0,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/posts\/3469\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/media?parent=3469"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/categories?post=3469"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/tags?post=3469"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}