{"id":484,"date":"2009-12-14T21:53:37","date_gmt":"2009-12-14T20:53:37","guid":{"rendered":"http:\/\/carnet.causeur.fr\/antidote\/?p=484"},"modified":"2021-04-26T16:11:40","modified_gmt":"2021-04-26T14:11:40","slug":"questions-autour-dun-micro-cravate","status":"publish","type":"post","link":"https:\/\/blog.causeur.fr\/antidote\/questions-autour-dun-micro-cravate-484","title":{"rendered":"Questions autour d&#039;un micro-cravate"},"content":{"rendered":"<p>C&rsquo;est la dernier buzz sur la toile. Rachida Dati qui confie \u00e0 une amie au t\u00e9l\u00e9phone qu&rsquo;elle n&rsquo;en peut plus, qu&rsquo;il va y avoir un drame avant la fin de son mandat. Cette confession, la d\u00e9put\u00e9e europ\u00e9enne l&rsquo;a faite au t\u00e9l\u00e9phone. Elle ne se souvenait plus qu&rsquo;elle \u00e9tait munie d&rsquo;un micro-cravate. La cha\u00eene M6 a pris la d\u00e9cision de diffuser cette s\u00e9quence.<\/p>\n<p>Au printemps dernier, c&rsquo;\u00e9tait le d\u00e9put\u00e9 socialiste[1. On ne rit pas, dans le fond] Manuel Valls qui avait \u00e9t\u00e9 pi\u00e9g\u00e9 par un micro-cravate et une cam\u00e9ra de la cha\u00eene num\u00e9rique terrestre Direct8 pour l&rsquo;\u00e9mission Politiquement parlant. Il avait d\u00e9plor\u00e9 le manque <em>de whites et de blancos<\/em> au march\u00e9 de sa bonne ville d&rsquo;Evry.<\/p>\n<p>Bien s\u00fbr, on peut d\u00e9plorer le manque de classe de ces cha\u00eenes de t\u00e9l\u00e9 qui, au lieu de faire la part des choses entre ce qui rel\u00e8ve de la conversation priv\u00e9e et de la d\u00e9claration publique, diffusent ces s\u00e9quences. Les personnalit\u00e9s politiques se sentent flou\u00e9es, trahies.<\/p>\n<p>Pourtant, je ne serai pas du nombre qui plaignent Manuel et Rachida. Quand on accepte de poser un micro sur son v\u00eatement et d&rsquo;\u00eatre ensuite suivi toute une journ\u00e9e, on le fait dans un but pr\u00e9cis : appara\u00eetre naturel, coule, dans le vent. Et on prend des risques, beaucoup de risques. Car personne n&rsquo;est \u00e0 l&rsquo;abri d&rsquo;oublier qu&rsquo;il est enregistr\u00e9. Pis, et m\u00eame si le temps de r\u00e9sistance diff\u00e8re selon les personnes, tout le monde finit par oublier micro et cam\u00e9ra. C&rsquo;est m\u00eame le but de l&rsquo;exercice. Participer \u00e0 une \u00e9mission de t\u00e9l\u00e9-r\u00e9alit\u00e9 pour appara\u00eetre tel que dans sa vie priv\u00e9e.<\/p>\n<p>Donc, la question, crue, doit \u00eatre pos\u00e9e : les gens qui acceptent de participer \u00e0 de telles exp\u00e9riences ne seraient-ils pas un peu cons ?<\/p>\n<p>S&rsquo;ils le font en toute connaissance de cause, qu&rsquo;ils prennent le risque de livrer leur intimit\u00e9 \u00e0 tout moment, qu&rsquo;ils l&rsquo;acceptent en jugeant qu&rsquo;au bout du compte les avantages seront sup\u00e9rieurs aux inconv\u00e9nients, la politique \u00e9tant r\u00e9duite au concours de beaut\u00e9, int\u00e9rieure en l&rsquo;occurrence, ils ne sont pas cons mais dangereux. Dangereux pour notre d\u00e9mocratie. Dangereux pour participer ainsi \u00e0 l&rsquo;effacement entre vie priv\u00e9e et vie publique.<\/p>\n<p>Si, en revanche, ils pensent que leur grande ma\u00eetrise leur permettra d&rsquo;\u00e9chapper en toutes circonstances \u00e0 ce genre de m\u00e9saventure, ils p\u00e8chent alors par suffisance et, l\u00e0, on peut finalement conclure qu&rsquo;ils sont b\u00eates comme leurs pieds.<\/p>\n<p>Je ne sais dans quelle cat\u00e9gorie on doit ranger Rachida Dati et Manuel Valls. Ils ne figurent d&rsquo;ailleurs peut-\u00eatre pas forc\u00e9ment dans la m\u00eame. Dans les deux cas, il m&rsquo;appara\u00eet aujourd&rsquo;hui plut\u00f4t imprudent d&rsquo;accorder son suffrage \u00e0 ces personnalit\u00e9s.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M6 et Direct8 sans foi ni loi ? Ou Dati et Valls b\u00eates comme leurs pieds ?<\/p>\n","protected":false},"author":10,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":{"0":"post-484","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-sulfate"},"_links":{"self":[{"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/posts\/484","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/users\/10"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/comments?post=484"}],"version-history":[{"count":0,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/posts\/484\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/media?parent=484"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/categories?post=484"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.causeur.fr\/antidote\/wp-json\/wp\/v2\/tags?post=484"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}