{"id":4976,"date":"2024-05-09T08:34:13","date_gmt":"2024-05-09T06:34:13","guid":{"rendered":"https:\/\/blog.causeur.fr\/bonnetdane\/?p=4976"},"modified":"2024-05-10T15:48:34","modified_gmt":"2024-05-10T13:48:34","slug":"voix-graves-voix-aigues","status":"publish","type":"post","link":"https:\/\/blog.causeur.fr\/bonnetdane\/voix-graves-voix-aigues-4976","title":{"rendered":"Voix graves, voix aig\u00fces"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/blog.causeur.fr\/bonnetdane\/wp-content\/uploads\/sites\/25\/2024\/05\/18385585.jpg-r_1280_720-f_jpg-q_x-xxyxx.jpg\" alt=\"\" class=\"wp-image-5001\" srcset=\"https:\/\/blog.causeur.fr\/bonnetdane\/wp-content\/uploads\/sites\/25\/2024\/05\/18385585.jpg-r_1280_720-f_jpg-q_x-xxyxx.jpg 600w, https:\/\/blog.causeur.fr\/bonnetdane\/wp-content\/uploads\/sites\/25\/2024\/05\/18385585.jpg-r_1280_720-f_jpg-q_x-xxyxx-300x200.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Eros, qui est un polisson, m\u2019a souvent fait tomber amoureux de cr\u00e9atures r\u00e9sidant au loin. Quand j\u2019habitais Paris, B*** vivait pr\u00e8s d\u2019Angoul\u00eame, V*** \u00e0 Marseille. Plus tard, quand je fus revenu \u00e0 Marseille (et que, <em>fatalitas<\/em>, V*** m\u2019\u00e9tait sortie de la t\u00eate), j\u2019entretins avec M***, qui vivait \u00e0 Paris, une liaison qui, par la force des choses, se passait plus souvent au t\u00e9l\u00e9phone que sous la couette.<br>Alors nous nous parlions, interminablement, \u00e0 nous dire \u00ab ces jolis riens qui sont tout \u00bb. Quand le regard ou la peau font d\u00e9faut, il ne reste que la voix pour porter la sensualit\u00e9. Combien de fois l\u2019une ou l\u2019autre montait ainsi jusqu\u2019\u00e0 l\u2019orgasme au seul son de ma voix \u2014 accompagn\u00e9e d\u2019un petit jeu de doigts rythm\u00e9 par les vibrations des cordes vocales\u2026 <br><br>C\u2019est \u00e0 peu pr\u00e8s le dilemme de Rom\u00e9o ou de Cyrano au pied du balcon de Juliette ou de Roxane. \u00ab C\u2019est vrai que vous avez une toute autre voix \u00bb, remarque Roxane, quand Cyrano s\u2019est substitu\u00e9 \u00e0 cette triple buse de Christian pour parler \u00e0 sa place, dans le noir. Je le crois bien ! Et c\u2019est la clef du choix des acteurs : on n\u2019imagine pas Fabrice Luchini, avec sa voix souvent haut perch\u00e9e et ses modulations infinies, jouer Cyrano ou Rom\u00e9o. Imaginez notre histrion national articuler s\u00e9rieusement :<br><br>\u00ab It is my soul that calls upon my name:<br>How silver-sweet sound lovers&rsquo; tongues by night,<br>Like softest music to attending ears! \u00bb<br><br>La sc\u00e8ne du balcon \u2014 et pour cause \u2014 est parsem\u00e9e de r\u00e9flexions sur le son de la voix. Au tout d\u00e9but du dialogue, Juliette lance :<br><br>\u00ab My ears have not yet drunk a hundred words<br>Of that tongue&rsquo;s utterance, yet I know the sound:<br>Art thou not Romeo and a Montague ? \u00bb<br><br>Une bonne part de l\u2019attention que m\u2019accord\u00e8rent pendant 45 ans mes \u00e9l\u00e8ves, ou d\u00e9sormais les publics devant lesquels je m\u2019exprime, sur les ondes ou en direct, tient \u00e0 la modulation basse de ma voix, objet d\u2019un travail infini vers la fin de l\u2019adolescence, quand les cordes vocales se sont enfin \u00e9paissies et que le larynx est descendu dans le cou\u2026 Je plains les enseignants qui n\u2019ont pas une voix en accord avec cette n\u00e9cessit\u00e9 constante de s\u00e9duire qu\u2019on appelle en vrai la p\u00e9dagogie. <br><br>Faisons bri\u00e8vement l\u2019histoire de la voix.<br>Les b\u00e9b\u00e9s, gar\u00e7ons ou filles, ont \u00e0 peu pr\u00e8s la m\u00eame voix. Ils crient \u00e0 440 hertz. Et jusqu\u2019\u00e0 la pubert\u00e9, leurs voix sont tr\u00e8s proches \u2014 c\u2019est ce qui poussait les ma\u00eetres de chapelle \u00e0 sugg\u00e9rer aux parents de castrer leur rejeton, afin que l\u2019afflux prochain de testost\u00e9rone n\u2019ab\u00eeme pas le son m\u00e9lodieux du rossignol humain. Mais sans intervention ext\u00e9rieure, la voix des gar\u00e7ons va peu \u00e0 peu passer dans le grave (avec au tout d\u00e9but des hauts et des bas assez comiques), tandis que celle des filles, sous l\u2019influence des \u0153strog\u00e8nes, restera dans les teintes claires et cristallines.<br>Ce n\u2019est pas un hasard si j\u2019\u00e9voque le r\u00f4le des hormones. La voix est un facteur essentiel de la s\u00e9duction \u2014 et il faut \u00eatre singuli\u00e8rement cr\u00e9tin pour croire que l\u2019essentiel des relations humaines ne tourne pas autour de la reproduction et de la gymnastique qui tourne autour de cette intention. Les m\u00e2les reproducteurs ont une voix basse \u2014 <a href=\"https:\/\/www.youtube.com\/watch?v=Umm3jfVsYv0\">\u00e9coutez le brame des cerfs<\/a> \u2014, et singuli\u00e8rement monocorde : des \u00e9tudes concluantes ont prouv\u00e9 que les femmes pr\u00e9f\u00e8rent le ton de Clint Eastwood \u00e0 celui, glapissant, que prend (intentionnellement) Jack Lemmon dans <em>Some like it hot<\/em>. <a href=\"https:\/\/www.youtube.com\/watch?v=gfGT4azZ0bQ\">Dans la sc\u00e8ne finale<\/a>, lorsque Jack Lemmon passe d&rsquo;un coup du registre glapissant \u00e0 son intonation virile, on sent merveilleusement la diff\u00e9rence fondamentale. D\u00e9monstration parfaite du fait que la femme se caract\u00e9rise par des intonations et une variabilit\u00e9 bien plus intense que l\u2019homme. \u00c0 tel point que la <a href=\"https:\/\/www.dailymotion.com\/video\/x1vorl\">voix tapiss\u00e9e de tabac et de luxure de Lauren Bacall <\/a>(travaill\u00e9e de son propre aveu \u00e0 la cigarette pendant trois semaines avant le tournage, entretenue plus tard au whisky) fait planer une ambigu\u00eft\u00e9 sur ce que Bogart (ou du moins les personnages qu\u2019il interpr\u00e9tait) trouvait en elle.<br><br>On se souvient, dans <em>Singing in the rain<\/em>, de <a href=\"https:\/\/www.youtube.com\/watch?v=NTFigYMQxnA\">la performance de Jean Hagen<\/a> (qui lui valut une nomination aux Oscars) dans le r\u00f4le de cette star du muet refoul\u00e9e \u00e0 l\u2019arriv\u00e9e du parlant \u00e0 cause de sa voix haut perch\u00e9e et z\u00e9zayante. Une voix de cr\u00e9celle, selon l\u2019expression consacr\u00e9e \u2014 sans que qui que ce soit se souvienne de ce qu\u2019est une cr\u00e9celle. Une heure de cours avec ce type de voix, c\u2019est la fuite assur\u00e9e.<br><br>N&rsquo;en d\u00e9plaise aux imb\u00e9ciles qui s\u2019insurgent contre les repr\u00e9sentations \u00ab genr\u00e9es \u00bb, comme ils disent, les femmes ont une voix plus haute et plus modul\u00e9e que les hommes, et les vrais s\u00e9ducteurs une voix plus basse, et plus monocorde \u2014 une voix susceptible de calmer les b\u00e9b\u00e9s et d\u2019hypnotiser les donzelles. Essayez George Clooney. \u00c0 la pubert\u00e9, la voix des filles descend en g\u00e9n\u00e9ral de deux tons, celle des gar\u00e7ons d\u2019un octave. Sopranos d\u2019un c\u00f4t\u00e9, t\u00e9nors de l\u2019autre. C\u2019est sur ce crit\u00e8re vocal que se greffent, ensuite, les man\u0153uvres d\u2019approche.<br><br>Evidemment, certaines pratiques (l\u2019alcool, le tabac, le style camionneur) peuvent faire baisser la voix des femmes. Mais de fa\u00e7on raisonnable : Garbo ne glapissait pas, elle jouait avec un ton grave et sensuel, et c\u2019\u00e9tait pour cette voix qu\u2019on lui \u00e9crivait ses r\u00f4les. <br><br>Reste l\u2019accent, qui peut ruiner la plus belle voix. C\u2019est apr\u00e8s mon entr\u00e9e \u00e0 Normale Sup que j\u2019ai travaill\u00e9 ma voix de fa\u00e7on \u00e0 ne laisser subsister quelques intonations sudistes qu\u2019\u00e0 volont\u00e9. Ava Gardner raconte dans ses M\u00e9moires qu\u2019en arrivant \u00e0 Hollywood, elle a pris un nombre infini de le\u00e7ons pour effacer son accent sudiste (elle venait de Caroline du Nord) et acqu\u00e9rir l\u2019intonation parfaite de la femme fatale. \u00c7a nous a valu <a href=\"http:\/\/Pandora, l\u2019un des chefs d\u2019\u0153uvre d\u2019Albert Lewin\"><em>Pandora<\/em>, l\u2019un des chefs d\u2019\u0153uvre d\u2019Albert Lewin<\/a> \u2014 la voix feutr\u00e9e de Gardner, la voix de m\u00e9tal doux de James Mason. Comment faire comprendre cela \u00e0 des adolescents glapissants ?<br><br>La voix est ce qui change en dernier. Les vieilles personnes, de l\u2019un ou l\u2019autre sexe, finissent par avoir les m\u00eames intonations \u2014 comme les b\u00e9b\u00e9s qu\u2019ils furent autrefois. On sait alors que la fin s\u2019approche, lorsque l\u2019on a abandonn\u00e9 le dernier instrument de s\u00e9duction.<br><br>Jean-Paul Brighelli<br><\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"760\" src=\"https:\/\/blog.causeur.fr\/bonnetdane\/wp-content\/uploads\/sites\/25\/2024\/05\/Capture-de\u0301cran-2024-05-09-a\u0300-08.33.43-1024x760.png\" alt=\"\" class=\"wp-image-5004\" srcset=\"https:\/\/blog.causeur.fr\/bonnetdane\/wp-content\/uploads\/sites\/25\/2024\/05\/Capture-de\u0301cran-2024-05-09-a\u0300-08.33.43-1024x760.png 1024w, https:\/\/blog.causeur.fr\/bonnetdane\/wp-content\/uploads\/sites\/25\/2024\/05\/Capture-de\u0301cran-2024-05-09-a\u0300-08.33.43-300x223.png 300w, https:\/\/blog.causeur.fr\/bonnetdane\/wp-content\/uploads\/sites\/25\/2024\/05\/Capture-de\u0301cran-2024-05-09-a\u0300-08.33.43-768x570.png 768w, https:\/\/blog.causeur.fr\/bonnetdane\/wp-content\/uploads\/sites\/25\/2024\/05\/Capture-de\u0301cran-2024-05-09-a\u0300-08.33.43-1536x1141.png 1536w, https:\/\/blog.causeur.fr\/bonnetdane\/wp-content\/uploads\/sites\/25\/2024\/05\/Capture-de\u0301cran-2024-05-09-a\u0300-08.33.43-485x360.png 485w, https:\/\/blog.causeur.fr\/bonnetdane\/wp-content\/uploads\/sites\/25\/2024\/05\/Capture-de\u0301cran-2024-05-09-a\u0300-08.33.43-696x517.png 696w, https:\/\/blog.causeur.fr\/bonnetdane\/wp-content\/uploads\/sites\/25\/2024\/05\/Capture-de\u0301cran-2024-05-09-a\u0300-08.33.43-1068x793.png 1068w, https:\/\/blog.causeur.fr\/bonnetdane\/wp-content\/uploads\/sites\/25\/2024\/05\/Capture-de\u0301cran-2024-05-09-a\u0300-08.33.43-566x420.png 566w, https:\/\/blog.causeur.fr\/bonnetdane\/wp-content\/uploads\/sites\/25\/2024\/05\/Capture-de\u0301cran-2024-05-09-a\u0300-08.33.43-80x60.png 80w, https:\/\/blog.causeur.fr\/bonnetdane\/wp-content\/uploads\/sites\/25\/2024\/05\/Capture-de\u0301cran-2024-05-09-a\u0300-08.33.43-265x198.png 265w, https:\/\/blog.causeur.fr\/bonnetdane\/wp-content\/uploads\/sites\/25\/2024\/05\/Capture-de\u0301cran-2024-05-09-a\u0300-08.33.43.png 1546w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Eros, qui est un polisson, m\u2019a souvent fait tomber amoureux de cr\u00e9atures r\u00e9sidant au loin. Quand j\u2019habitais Paris, B*** vivait pr\u00e8s d\u2019Angoul\u00eame, V*** \u00e0 Marseille. Plus tard, quand je fus revenu \u00e0 Marseille (et que, fatalitas, V*** m\u2019\u00e9tait sortie de la t\u00eate), j\u2019entretins avec M***, qui vivait \u00e0 Paris, une liaison qui, par la force [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[3828,3825,1323,3822,3826],"class_list":["post-4976","post","type-post","status-publish","format-standard","hentry","category-non-classe","tag-certains-laiment-chaud","tag-lauren-bacall","tag-seduction","tag-voix-graves-voix-aigues","tag-voix-masculines-voix-feminines"],"_links":{"self":[{"href":"https:\/\/blog.causeur.fr\/bonnetdane\/wp-json\/wp\/v2\/posts\/4976","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.causeur.fr\/bonnetdane\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.causeur.fr\/bonnetdane\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.causeur.fr\/bonnetdane\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.causeur.fr\/bonnetdane\/wp-json\/wp\/v2\/comments?post=4976"}],"version-history":[{"count":0,"href":"https:\/\/blog.causeur.fr\/bonnetdane\/wp-json\/wp\/v2\/posts\/4976\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.causeur.fr\/bonnetdane\/wp-json\/wp\/v2\/media?parent=4976"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.causeur.fr\/bonnetdane\/wp-json\/wp\/v2\/categories?post=4976"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.causeur.fr\/bonnetdane\/wp-json\/wp\/v2\/tags?post=4976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}