{"id":5670,"date":"2026-05-24T14:37:16","date_gmt":"2026-05-24T12:37:16","guid":{"rendered":"https:\/\/blog.causeur.fr\/bonnetdane\/?p=5670"},"modified":"2026-05-24T14:37:16","modified_gmt":"2026-05-24T12:37:16","slug":"de-face-et-de-dos-petite-histoire-de-la-pudeur","status":"publish","type":"post","link":"https:\/\/blog.causeur.fr\/bonnetdane\/de-face-et-de-dos-petite-histoire-de-la-pudeur-5670","title":{"rendered":"De face et de dos : petite histoire de la pudeur"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Jean-L\u00e9on G\u00e9r\u00f4me, <em>Vente d\u2019esclaves \u00e0 Rome<\/em>, 1884<br><br><br>Quand le marchand vous met \u00e0 nu, que cacher ?<br>G\u00e9r\u00f4me n\u2019h\u00e9site pas : l\u2019esclave propos\u00e9e \u00e0 la vente se cache le visage. La honte r\u00e9side dans l\u2019identification, pas dans l\u2019exhibition forc\u00e9e de tel ou tel tr\u00e9sor de l\u2019anatomie. Elle est dans le nom que l\u2019on pourrait mettre sur un visage \u2014 ce qui nous incite \u00e0 penser que la jeune fille pourrait \u00eatre reconnue, qu\u2019elle est une Romaine punie par son ma\u00eetre. Vendue comme esclave, aupr\u00e8s d\u2019un public averti, apr\u00e8s avoir \u00e9t\u00e9 soumise. Pour la ch\u00e2tier ou simplement par n\u00e9cessit\u00e9 financi\u00e8re. Ou par jeu.<br><br>Dans la toile de 1884, nous sommes du c\u00f4t\u00e9 des spectateurs ou des amateurs susceptibles d\u2019ench\u00e9rir (je suis fascin\u00e9 par ce mot, qui \u00e9voque \u00e0 la fois la transaction financi\u00e8re et le sentiment \u2014 comme si dans tout sentiment se nichait une transaction).<br><br>D\u2019un point de vue strictement pictural, G\u00e9r\u00f4me fait preuve d\u2019une cr\u00e9ativit\u00e9 mesur\u00e9e. Non seulement il se conforme aux codes de l\u2019Acad\u00e9misme le plus strict \u2014 et je rappelle que j\u2019entretiens sur Facebook une page intitul\u00e9e <em><a href=\"https:\/\/www.facebook.com\/groups\/518494726484477\">Gloire \u00e0 l\u2019Art pompier <\/a><\/em>\u2014, mais il se contente de romaniser ce qu\u2019il avait orientalis\u00e9 dans son tableau de 1866 sur le <em>March\u00e9 d\u2019esclaves<\/em> :<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"764\" height=\"1024\" src=\"https:\/\/blog.causeur.fr\/bonnetdane\/wp-content\/uploads\/sites\/25\/2026\/05\/Jean-Leon_Gerome_-_Le_Marche_desclaves-1-764x1024.jpg\" alt=\"\" class=\"wp-image-5699\" srcset=\"https:\/\/blog.causeur.fr\/bonnetdane\/wp-content\/uploads\/sites\/25\/2026\/05\/Jean-Leon_Gerome_-_Le_Marche_desclaves-1-764x1024.jpg 764w, https:\/\/blog.causeur.fr\/bonnetdane\/wp-content\/uploads\/sites\/25\/2026\/05\/Jean-Leon_Gerome_-_Le_Marche_desclaves-1-224x300.jpg 224w, https:\/\/blog.causeur.fr\/bonnetdane\/wp-content\/uploads\/sites\/25\/2026\/05\/Jean-Leon_Gerome_-_Le_Marche_desclaves-1-768x1030.jpg 768w, https:\/\/blog.causeur.fr\/bonnetdane\/wp-content\/uploads\/sites\/25\/2026\/05\/Jean-Leon_Gerome_-_Le_Marche_desclaves-1-1146x1536.jpg 1146w, https:\/\/blog.causeur.fr\/bonnetdane\/wp-content\/uploads\/sites\/25\/2026\/05\/Jean-Leon_Gerome_-_Le_Marche_desclaves-1-313x420.jpg 313w, https:\/\/blog.causeur.fr\/bonnetdane\/wp-content\/uploads\/sites\/25\/2026\/05\/Jean-Leon_Gerome_-_Le_Marche_desclaves-1-696x933.jpg 696w, https:\/\/blog.causeur.fr\/bonnetdane\/wp-content\/uploads\/sites\/25\/2026\/05\/Jean-Leon_Gerome_-_Le_Marche_desclaves-1-1068x1432.jpg 1068w, https:\/\/blog.causeur.fr\/bonnetdane\/wp-content\/uploads\/sites\/25\/2026\/05\/Jean-Leon_Gerome_-_Le_Marche_desclaves-1.jpg 1280w\" sizes=\"auto, (max-width: 764px) 100vw, 764px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Et certes l\u2019orientalisme a longtemps \u00e9t\u00e9 pourvoyeur (autre mot magnifique qui dit bien ce qu\u2019il veut dire : il est pour les voyeurs) de beaut\u00e9s d\u00e9nud\u00e9es. Nous avons vu pr\u00e9c\u00e9demment que la police imp\u00e9riale traquait les photographes amateurs de nymphettes \u2014 et Nadar ne fut pas le dernier \u00e0 fournir aux peintres de sujets d\u00e9j\u00e0 install\u00e9s dans la pose souhait\u00e9e. Ainsi \u00ab Mariette \u00bb \u2014 ou Christine Roux, si vous voulez l\u2019\u00e9tat-civil complet : <\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"664\" height=\"1024\" src=\"https:\/\/blog.causeur.fr\/bonnetdane\/wp-content\/uploads\/sites\/25\/2026\/05\/Nadar-1820-1910-MarietteChristine-Roux-nue-1855-1-664x1024.jpg\" alt=\"\" class=\"wp-image-5704\" srcset=\"https:\/\/blog.causeur.fr\/bonnetdane\/wp-content\/uploads\/sites\/25\/2026\/05\/Nadar-1820-1910-MarietteChristine-Roux-nue-1855-1-664x1024.jpg 664w, https:\/\/blog.causeur.fr\/bonnetdane\/wp-content\/uploads\/sites\/25\/2026\/05\/Nadar-1820-1910-MarietteChristine-Roux-nue-1855-1-194x300.jpg 194w, https:\/\/blog.causeur.fr\/bonnetdane\/wp-content\/uploads\/sites\/25\/2026\/05\/Nadar-1820-1910-MarietteChristine-Roux-nue-1855-1-768x1185.jpg 768w, https:\/\/blog.causeur.fr\/bonnetdane\/wp-content\/uploads\/sites\/25\/2026\/05\/Nadar-1820-1910-MarietteChristine-Roux-nue-1855-1-995x1536.jpg 995w, https:\/\/blog.causeur.fr\/bonnetdane\/wp-content\/uploads\/sites\/25\/2026\/05\/Nadar-1820-1910-MarietteChristine-Roux-nue-1855-1-272x420.jpg 272w, https:\/\/blog.causeur.fr\/bonnetdane\/wp-content\/uploads\/sites\/25\/2026\/05\/Nadar-1820-1910-MarietteChristine-Roux-nue-1855-1-696x1074.jpg 696w, https:\/\/blog.causeur.fr\/bonnetdane\/wp-content\/uploads\/sites\/25\/2026\/05\/Nadar-1820-1910-MarietteChristine-Roux-nue-1855-1.jpg 1000w\" sizes=\"auto, (max-width: 664px) 100vw, 664px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Mais c\u2019est l\u00e0 la pierre de touche de la diff\u00e9rence entre l\u2019art et la photographie qui n\u2019est jamais que repr\u00e9sentation du r\u00e9el. Voir ce qu\u2019en dit Baudelaire dans son <em>Salon<\/em> de 1859 :<br><br>\u00ab Dans ces jours d\u00e9plorables, une industrie nouvelle se produisit, qui ne contribua pas peu \u00e0 confirmer la sottise dans sa foi et \u00e0 ruiner ce qui pouvait rester de divin dans l\u2019esprit fran\u00e7ais. Cette foule idol\u00e2tre postulait un id\u00e9al digne d\u2019elle et appropri\u00e9 \u00e0 sa nature, cela est bien entendu. En mati\u00e8re de peinture et de statuaire, le Credo actuel des gens du monde, surtout en France (et je ne crois pas que qui que ce soit ose affirmer le contraire), est celui-ci : \u00ab Je crois \u00e0 la nature et je ne crois qu\u2019\u00e0 la nature (il y a de bonnes raisons pour cela). Je crois que l\u2019art est et ne peut \u00eatre que la reproduction exacte de la nature (une secte timide et dissidente veut que les objets de la nature r\u00e9pugnante soient \u00e9cart\u00e9s, ainsi un pot de chambre ou un squelette).<br>\u00ab Ainsi l\u2019industrie qui nous donnerait un r\u00e9sultat identique \u00e0 la nature serait l\u2019art absolu. \u00bb Un Dieu vengeur a exauc\u00e9 les v\u0153ux de cette multitude. Daguerre fut son messie. Et alors elle se dit : \u00ab Puisque la photographie nous donne toutes les garanties d\u00e9sirables d\u2019exactitude (ils croient cela, les insens\u00e9s !), l\u2019art c\u2019est la photographie \u00bb.<br><br>L\u2019Art n\u2019est pas la nature, alors que la photographie la restitue \u00ac comme on restitue un repas trop copieux. La photographie est un d\u00e9gueulis de r\u00e9alit\u00e9.<br><br>Mais dans la version invers\u00e9e de 1886<br><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"629\" height=\"700\" src=\"https:\/\/blog.causeur.fr\/bonnetdane\/wp-content\/uploads\/sites\/25\/2026\/05\/Gerome_Vente_desclaves_a_Rome_1886_5614092862.jpg\" alt=\"\" class=\"wp-image-5707\" srcset=\"https:\/\/blog.causeur.fr\/bonnetdane\/wp-content\/uploads\/sites\/25\/2026\/05\/Gerome_Vente_desclaves_a_Rome_1886_5614092862.jpg 629w, https:\/\/blog.causeur.fr\/bonnetdane\/wp-content\/uploads\/sites\/25\/2026\/05\/Gerome_Vente_desclaves_a_Rome_1886_5614092862-270x300.jpg 270w, https:\/\/blog.causeur.fr\/bonnetdane\/wp-content\/uploads\/sites\/25\/2026\/05\/Gerome_Vente_desclaves_a_Rome_1886_5614092862-377x420.jpg 377w\" sizes=\"auto, (max-width: 629px) 100vw, 629px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><br>nous voici, nous amateurs de peinture, de l\u2019autre c\u00f4t\u00e9 du spectacle. La femme se cache toujours le visage afin que les clients ne la reconnaissent pas, mais ce faisant, elle exhibe pour nous les deux globes satin\u00e9s entre lesquels niche la bouche d\u2019ombre, comme disait Hugo qui en avait vu quelques-unes\u2026 L\u2019espace se d\u00e9multiplie : il y a la foule des clients d\u2019un c\u00f4t\u00e9, et de l\u2019autre, la foule des vrais amateurs de beaut\u00e9, qui guettent les r\u00e9v\u00e9lations de cette fente proph\u00e9tique \u2014 le trou de la Sibylle, dit Rabelais. C\u2019est au chapitre 17 du <em>Tiers Livre<\/em>. Apr\u00e8s avoir \u00e9cout\u00e9 la pr\u00e9diction obscure de la Sibylle, Panurge et Epist\u00e9mon assistent \u00e0 son d\u00e9part :<br>\u00ab Ces parolles dictes, se retira en sa tesni\u00e8re, et sus le perron de la porte se recoursa, robbe, cotte et chemise jusques aux escelles, et leurs monstrait son cul. Panurge l\u2019aperceut, et dist \u00e0 \u00c9pist\u00e9mon  : \u00ab Par le sambre guoy de bois, voyl\u00e0 le trou de la Sibylle \u00bb. \u00bb<br><br>Inutile de rappeler qu\u2019il s\u2018agit d\u2019une allusion \u00e0 la Sibylle de Virgile (<em>En\u00e9ide<\/em>, chant III, vers 442 et sq.) : <br>\u00ab Tu pourras y voir une pr\u00eatresse en d\u00e9lire qui, au fond de son antre, chante les destin\u00e9es, et dont elle confie \u00e0 des feuilles d\u2019arbre les lettres et les mots. Tous les oracles que la vierge a trac\u00e9s sur ces feuilles, elle les range en bon ordre et les met \u00e0 part dans sa caverne. Ils restent en place sans se d\u00e9ranger. Mais que les gonds viennent \u00e0 pivoter, et la porte laissera un vent l\u00e9ger les soulever et bouleverser leur tendre frondaison. Apr\u00e8s quoi la vierge n\u2019essaie pas de les attraper quand ils voltigent dans sa caverne et ne se soucie jamais de les remettre \u00e0 leur place ni de les r\u00e9unir : on s\u2019en repart sans avoir obtenu de consultation et on ne pense que pis du si\u00e8ge de la Sibylle. \u00bb (trad. Paul Veyne).<br><br>Ce \u00ab vent l\u00e9ger \u00bb, dans cette histoire de fesses, appelle invinciblement l\u2019id\u00e9e du pet \u2014 seule expression directe et toute rabelaisienne de la proph\u00e9tesse, dont l\u2019appr\u00e9ciation et l\u2019interpr\u00e9tation sont laiss\u00e9es au pauvre qu\u00e9mandeur de destin.<br>Et face \u00e0 ces fesses (l\u2019histoire du tableau n\u2019est-elle pas une dialectique de face et de fesses ?), que sommes-nous d\u2019autre ?<br><br>Jean-Paul Brighelli<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Jean-L\u00e9on G\u00e9r\u00f4me, Vente d\u2019esclaves \u00e0 Rome, 1884 Quand le marchand vous met \u00e0 nu, que cacher ?G\u00e9r\u00f4me n\u2019h\u00e9site pas : l\u2019esclave propos\u00e9e \u00e0 la vente se cache le visage. La honte r\u00e9side dans l\u2019identification, pas dans l\u2019exhibition forc\u00e9e de tel ou tel tr\u00e9sor de l\u2019anatomie. Elle est dans le nom que l\u2019on pourrait mettre sur [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":5694,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[2696,4590,1102,1864,4591],"class_list":["post-5670","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classe","tag-baudelaire","tag-de-face-et-de-dos","tag-jean-leon-gerome","tag-nadar","tag-trou-de-la-sibylle"],"_links":{"self":[{"href":"https:\/\/blog.causeur.fr\/bonnetdane\/wp-json\/wp\/v2\/posts\/5670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.causeur.fr\/bonnetdane\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.causeur.fr\/bonnetdane\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.causeur.fr\/bonnetdane\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.causeur.fr\/bonnetdane\/wp-json\/wp\/v2\/comments?post=5670"}],"version-history":[{"count":0,"href":"https:\/\/blog.causeur.fr\/bonnetdane\/wp-json\/wp\/v2\/posts\/5670\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.causeur.fr\/bonnetdane\/wp-json\/wp\/v2\/media\/5694"}],"wp:attachment":[{"href":"https:\/\/blog.causeur.fr\/bonnetdane\/wp-json\/wp\/v2\/media?parent=5670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.causeur.fr\/bonnetdane\/wp-json\/wp\/v2\/categories?post=5670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.causeur.fr\/bonnetdane\/wp-json\/wp\/v2\/tags?post=5670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}