{"id":397,"date":"2017-03-13T17:18:37","date_gmt":"2017-03-13T17:18:37","guid":{"rendered":"http:\/\/blog.causeur.fr\/lavoixdenosmaitres\/?p=397"},"modified":"2021-04-23T15:35:15","modified_gmt":"2021-04-23T13:35:15","slug":"censure-aux-quotidiens","status":"publish","type":"post","link":"https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/censure-aux-quotidiens-397","title":{"rendered":"Censure aux quotidiens"},"content":{"rendered":"<p>Premi\u00e8res victimes\u00a0: les journalistes, les vrais.<\/p>\n<p><a href=\"http:\/\/blog.causeur.fr\/lavoixdenosmaitres\/files\/2017\/03\/censur\u00e9.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-398\" title=\"censur\u00e9\" src=\"http:\/\/blog.causeur.fr\/lavoixdenosmaitres\/files\/2017\/03\/censur\u00e9.jpg\" alt=\"\" width=\"1300\" height=\"732\" srcset=\"https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-content\/uploads\/sites\/27\/2017\/03\/censur\u00e9.jpg 1300w, https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-content\/uploads\/sites\/27\/2017\/03\/censur\u00e9-300x168.jpg 300w, https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-content\/uploads\/sites\/27\/2017\/03\/censur\u00e9-1024x576.jpg 1024w, https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-content\/uploads\/sites\/27\/2017\/03\/censur\u00e9-500x281.jpg 500w\" sizes=\"auto, (max-width: 1300px) 100vw, 1300px\" \/><\/a>J\u2019ai parl\u00e9 trop vite.<!--more--><\/p>\n<p>Il y a quelques jours, je m\u2019entretenais avec Philippe Delaroche \u00e0 l\u2019occasion d\u2019une interview pr\u00e9-enregistr\u00e9e pour <a href=\"https:\/\/radionotredame.net\/emissions\/decryptage\/\" target=\"_blank\" rel=\"noopener\">l\u2019\u00e9mission \u00ab\u00a0D\u00e9cryptage\u00a0\u00bb qu\u2019il dirige sur RND<\/a>. Il me demandait de commenter l\u2019accueil qu\u2019a re\u00e7u mon livre dans les m\u00e9dias. Je lui ai r\u00e9pondu que, \u00e0 ma grande surprise, <em>La<\/em> <em>Langue des m\u00e9dias<\/em> \u00e9tait globalement tr\u00e8s bien re\u00e7u par la presse, signe, peut-\u00eatre, que les temps \u00e9taient en train de changer. En effet, j\u2019en suis arriv\u00e9e au point o\u00f9 je peux me payer le luxe de d\u00e9cliner des invitations m\u00e9diatiques au lieu de bousculer, s\u00e9ance tenante, tout l\u2019emploi du temps familial pour me ruer sur un micro\u00a0!<\/p>\n<p>Comme Philippe Delaroche me rappelait la tentative de nazification dont j\u2019avais fait l\u2019objet dans l\u2019<em>Obs<\/em>, il y a quelques mois, je lui r\u00e9pondis, ce qui est vrai, que cet \u00e9pisode avait formidablement contribu\u00e9 au succ\u00e8s du livre. Le fait est que la journaliste, si vraiment elle avait voulu me nuire, n&rsquo;aurait jamais \u00e9crit un mot au sujet de l&rsquo;ouvrage. On me r\u00e9torque, en g\u00e9n\u00e9ral, que c\u2019est plus <a title=\"Comment L\u2019Obs m\u2019a diabolis\u00e9e\" href=\"http:\/\/blog.causeur.fr\/lavoixdenosmaitres\/comment-lobs-ma-diabolisee-007.html\" target=\"_blank\" rel=\"noopener\">ma r\u00e9ponse publi\u00e9e par <em>Causeur<\/em><\/a>, que l&rsquo;article sign\u00e9 Anne Crignon, qui a stimul\u00e9 les ventes de l\u2019ouvrage. Peut-\u00eatre, mais encore fallait-il qu\u2019on m\u2019e\u00fbt procur\u00e9 l\u2019occasion de l\u2019\u00e9crire. Et pour cela, je demeure tr\u00e8s reconnaissante envers cette journaliste.<\/p>\n<p>Que certains m\u00e9dias (notamment les plus fr\u00e9quemment critiqu\u00e9s dans le livre) persistassent \u00e0 m\u2019ignorer \u00e9tait parfaitement normal. Mais je n\u2019avais fait l\u2019objet d\u2019aucune censure. <strong>Les r\u00e9ponses que j\u2019ai donn\u00e9es en interview n\u2019ont jamais \u00e9t\u00e9 ni d\u00e9form\u00e9es, ni manipul\u00e9es afin de biaiser ma pens\u00e9e, ni abusivement tronqu\u00e9es, y compris quand mon interlocuteur manifestait une forme de scepticisme, de suspicion, voire de d\u00e9fiance \u00e0 mon \u00e9gard<\/strong>. <strong>Toutes les occasions d\u2019exposer mon travail qui m\u2019ont \u00e9t\u00e9 offertes dans la presse ont donn\u00e9 lieu \u00e0 publication, sans rencontrer d\u2019opposition.<\/strong><\/p>\n<p><strong>Jusqu\u2019\u00e0 maintenant.<\/strong><\/p>\n<p>Au d\u00e9tour d\u2019une journ\u00e9e bien charg\u00e9e, j\u2019avais accord\u00e9 un entretien \u00e0 un grand quotidien. A la suite de quoi, plus de nouvelles. Concentr\u00e9e sur une s\u00e9rie de conf\u00e9rences pr\u00e9vues de longue date, qui m\u2019ont bien occup\u00e9e ces derniers temps, j\u2019avais presque oubli\u00e9 cet article et quand j\u2019y repensai r\u00e9cemment, je me dis que, sans doute, il avait \u00e9t\u00e9 publi\u00e9 sans que j\u2019en sois inform\u00e9e, ou qu\u2019un autre sujet, plus important, s\u2019\u00e9tait substitu\u00e9, au dernier moment, \u00e0 l\u2019article portant sur mon livre. <strong>Pas une seule seconde, je n\u2019ai pens\u00e9 que l\u2019on avait pu interdire la publication de cet article<\/strong>.<\/p>\n<p>Et voil\u00e0 quelques jours, je re\u00e7ois un courriel du journaliste qui m\u2019a interview\u00e9e pour ce quotidien.<\/p>\n<p><strong>C\u2019est lui qui emploie le mot \u00ab\u00a0censure\u00a0\u00bb.<\/strong><\/p>\n<div id=\"ligne\"><\/div>\n<p>Je lui dis ma surprise. Quel sens, quel int\u00e9r\u00eat y aurait-il \u00e0 censurer quelqu\u2019un que d\u2019autres grands m\u00e9dias ne censurent pas\u00a0? <strong>A peu pr\u00e8s au moment o\u00f9 j\u2019ai donn\u00e9 cette interview censur\u00e9e, je disposais d\u2019une pleine page dans <em>Marianne\u00a0<\/em>!<\/strong> Co\u00efncidence non moins cocasse, le jour-m\u00eame o\u00f9 je re\u00e7us son message \u00e0 la fois triste et courrouc\u00e9, me parvenait \u00e9galement un courriel sign\u00e9 d\u2019un haut dignitaire ma\u00e7onnique. Il me disait sa satisfaction suite \u00e0 la conf\u00e9rence \u00e0 laquelle j\u2019ai particip\u00e9 il y a quelques semaines, au si\u00e8ge du Grand-Orient de France. Comme je l\u2019ai soulign\u00e9 en introduction de mon expos\u00e9 ce jour-l\u00e0, le GOF aurait eu toutes les raisons imaginables de ne pas inviter quelqu\u2019un comme moi (\u00e0 commencer peut-\u00eatre par l\u2019article de Mme Crignon\u00a0!). J\u2019ai pourtant \u00e9t\u00e9 re\u00e7ue sans aucune animosit\u00e9 et, oserai-je le mot, avec une courtoisie qui a donn\u00e9 tort \u00e0 tous ceux qui m\u2019avaient d\u00e9conseill\u00e9 de \u00ab\u00a0foncer dans ce pi\u00e8ge\u00a0\u00bb. <strong>Il est d\u2019ailleurs assez rigolo que l\u2019on puisse tenir le m\u00eame propos au Grand Orient qu\u2019\u00e0 la f\u00eate de Radio Courtoisie et recevoir la m\u00eame approbation\u00a0! Cela r\u00e9v\u00e8le de mani\u00e8re flagrante l\u2019agacement g\u00e9n\u00e9ralis\u00e9 qu\u2019engendre le discours m\u00e9diatique.<\/strong> Un peu incr\u00e9dule, je pose donc au journaliste cette question en forme de boutade\u00a0: votre journal serait-il plus sectaire que la franc-ma\u00e7onnerie\u00a0?<\/p>\n<p>Il me r\u00e9pond. <strong>Face \u00e0 la r\u00e9action de son journal, il se dit\u00a0 \u00ab\u00a0constern\u00e9 mais pas surpris\u00a0\u00bb<\/strong>, m\u00eame s&rsquo;il n&rsquo;aurait \u00ab\u00a0jamais cru qu&rsquo;on lui ferait un jour ce coup-l\u00e0\u00a0\u00bb. Il tient \u00e0 ce que je sache qu\u2019il s\u2019est battu pour obtenir la parution de son article, arguant aupr\u00e8s de sa hi\u00e9rarchie que ce pourrait \u00eatre valorisant pour le journal que d\u2019offrir une petite place \u00e0 un discours critique vis-\u00e0-vis des m\u00e9dias. <strong>On lui a r\u00e9pondu que cette id\u00e9e \u00e9tait mal venue en cette p\u00e9riode<\/strong>.<\/p>\n<p>Tiens tiens\u2026<\/p>\n<p><strong>Il semble que ce journaliste\u00a0<strong>courageux <\/strong> se soit heurt\u00e9 au \u00ab Journaliste\u00a0\u00bb<\/strong>. Vous savez, celui dont je parle dans mon livre. Celui qui a abdiqu\u00e9 toute son \u00e9thique professionnelle au profit d\u2019un sens de la \u00ab responsabilit\u00e9\u00a0\u00bb consistant \u00e0 anticiper en permanence les r\u00e9actions suppos\u00e9es d\u2019un lectorat stupide et prompt \u00e0 mal penser, celui qui se dit que, les \u00e9lections approchant, il serait dangereux de donner une place \u00e0 ce qu\u2019on appelle commun\u00e9ment le \u00ab\u00a0discours\u00a0anti-m\u00e9dias\u00a0\u00bb (expression qui <strong>disqualifie un travail comme le mien en le fourrant dans le m\u00eame sac que tous les agit\u00e9s qui vitup\u00e8rent contre les \u00ab\u00a0journalopes\u00a0\u00bb et les \u00ab\u00a0merdias\u00a0\u00bb<\/strong>).<\/p>\n<p>Alors, je repense \u00e0 ce jeune journaliste qui \u00e9tait intervenu \u00e0 la fin d\u2019une de mes pr\u00e9sentations orales publiques. Il venait de claquer la porte d\u2019un grand quotidien car, disait-il, \u00ab\u00a0<strong>on peut passer la moiti\u00e9 d\u2019une conf\u00e9rence de r\u00e9daction \u00e0 se demander si l\u2019on va sortir telle info, jug\u00e9e trop susceptible de faire le jeu du Front National<\/strong>\u00a0\u00bb.<\/p>\n<p>Je repense \u00e0 un \u00e9pisode survenu alors que mon livre venait de para\u00eetre. Un quotidien aussi : contact\u00e9 par le service de communication de ma maison d\u2019\u00e9dition \u00e0 l\u2019occasion d\u2019une s\u00e9ance de d\u00e9dicaces, le journal promet d\u2019envoyer quelqu\u2019un. Un rendez-vous est fix\u00e9. Le journaliste me pose un lapin. Je ne m\u2019\u00e9tonne ni ne m\u2019offusque\u00a0; ce sont peut-\u00eatre les usages du m\u00e9tier et puis, qui suis-je pour exiger qu&rsquo;on s&rsquo;int\u00e9resse \u00e0 moi ? <strong>Le m\u00eame journaliste est contact\u00e9 par une grande librairie lors d\u2019une autre s\u00e9ance de d\u00e9dicaces. Il ne viendra jamais.<\/strong> \u00ab\u00a0Je ne comprends pas : en g\u00e9n\u00e9ral, il est toujours l\u00e0, je le connais bien \u00bb, me dira, g\u00ean\u00e9, le libraire. A l\u2019\u00e9poque, j&rsquo;\u00e9tais seulement toute stup\u00e9faite que tant de gens viennent me rencontrer et ach\u00e8tent mon livre. C\u2019est aujourd\u2019hui que je repense \u00e0 cet \u00e9pisode&#8230;<\/p>\n<p>Je repense aussi \u00e0 ce livre que j\u2019ai d\u00e9vor\u00e9\u00a0: <strong><em>\u00ab\u00a0Le Monde\u00a0\u00bb tel qu\u2019il est<\/em><\/strong>, r\u00e9dig\u00e9 par un journaliste, Michel Legris qui, apr\u00e8s avoir travaill\u00e9 durant 26 ans pour ce journal, \u00e9tablit (en 1976 !) un diagnostic alarmant et d\u00e9go\u00fbt\u00e9 de ce qu\u2019est devenu la conscience professionnelle des journalistes au sein de sa r\u00e9daction. Ainsi que j\u2019ai d\u00e9j\u00e0 eu l\u2019occasion de le dire, <strong>si j\u2019avais lu ce livre plus t\u00f4t, je n\u2019aurais probablement pas \u00e9crit <em>la Langue des m\u00e9dias<\/em><\/strong>. Comme disait mon copain La Bruy\u00e8re, \u00ab\u00a0tout est dit et l\u2019on vient trop tard\u00a0\u00bb. Si l\u2019on en croit Michel Legris, <strong>aux avant-postes de la d\u00e9gradation des m\u00e9dias en instruments d\u2019une propagande moralisante, simplificatrice et ab\u00eatissante, \u00e9tait <em>le Monde<\/em>, le quotidien de r\u00e9f\u00e9rence<\/strong>.<\/p>\n<p>Et je repense \u00e0 la fin de mon entretien avec Philippe Delaroche\u00a0: n\u2019y aura-t-il pas toujours, me demandait-il, une diff\u00e9rence entre l\u2019audiovisuel et la presse papier, cette derni\u00e8re fonctionnant moins dans l\u2019imm\u00e9diatet\u00e9\u00a0? Je r\u00e9pondis que le temps de la r\u00e9daction obligeait n\u00e9cessairement, tant soit peu, \u00e0 une r\u00e9flexion sur le choix des mots, que l\u2019espoir r\u00e9sidait peut-\u00eatre l\u00e0.<\/p>\n<p>J&rsquo;ai p\u00e9ch\u00e9 par g\u00e9n\u00e9ralisation. J\u2019ai oubli\u00e9 de pr\u00e9ciser ce que je constate \u00e0 pr\u00e9sent\u00a0: <strong>les quotidiens sont \u00e0 la presse \u00e9crite ce que les cha\u00eenes d\u2019information continue sont \u00e0 l\u2019audiovisuel.<\/strong><\/p>\n<p>Et je veux saluer ici <strong>la vaillance des vrais journalistes<\/strong>, ceux qu\u2019animent la curiosit\u00e9 humaine et le sens de l\u2019\u00e9coute, ceux qui savent faire fi des pr\u00e9jug\u00e9s entretenus par leur sph\u00e8re professionnelle, ceux qui doivent lutter au sein de leur propre r\u00e9daction pour avoir seulement le droit d\u2019exercer correctement leur m\u00e9tier, ceux, enfin, <strong>qui subissent une censure pratiqu\u00e9e par leurs propres confr\u00e8res au nom de principes qui ne devraient pas avoir droit de cit\u00e9 dans le monde de l\u2019information<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Premi\u00e8res victimes\u00a0: les journalistes, les vrais. J\u2019ai parl\u00e9 trop vite.<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[161,164,163,162],"class_list":{"0":"post-397","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-articles","7":"tag-censure","8":"tag-ethique-du-journalisme","9":"tag-journaux-quotidiens","10":"tag-presse-ecrite"},"_links":{"self":[{"href":"https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-json\/wp\/v2\/posts\/397","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-json\/wp\/v2\/comments?post=397"}],"version-history":[{"count":0,"href":"https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-json\/wp\/v2\/posts\/397\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-json\/wp\/v2\/media?parent=397"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-json\/wp\/v2\/categories?post=397"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-json\/wp\/v2\/tags?post=397"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}