{"id":461,"date":"2017-04-28T12:45:38","date_gmt":"2017-04-28T12:45:38","guid":{"rendered":"http:\/\/blog.causeur.fr\/lavoixdenosmaitres\/?p=461"},"modified":"2021-04-23T15:35:02","modified_gmt":"2021-04-23T13:35:02","slug":"il-y-a-censure-ou-bien-il-ny-a-pas-censure","status":"publish","type":"post","link":"https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/il-y-a-censure-ou-bien-il-ny-a-pas-censure-461","title":{"rendered":"Il y a censure ou bien il n&rsquo;y a pas censure"},"content":{"rendered":"<p>Comme disait Musset, il faut qu&rsquo;une porte soit ouverte ou ferm\u00e9e.<\/p>\n<p><a href=\"http:\/\/blog.causeur.fr\/lavoixdenosmaitres\/files\/2017\/04\/Barr\u00e9.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-462\" title=\"Barr\u00e9\" src=\"http:\/\/blog.causeur.fr\/lavoixdenosmaitres\/files\/2017\/04\/Barr\u00e9.jpg\" alt=\"\" width=\"825\" height=\"450\" srcset=\"https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-content\/uploads\/sites\/27\/2017\/04\/Barr\u00e9.jpg 825w, https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-content\/uploads\/sites\/27\/2017\/04\/Barr\u00e9-300x163.jpg 300w, https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-content\/uploads\/sites\/27\/2017\/04\/Barr\u00e9-500x272.jpg 500w\" sizes=\"auto, (max-width: 825px) 100vw, 825px\" \/><\/a>Dans cet article, je prends la d\u00e9fense d&rsquo;un chroniqueur de France Inter. D\u00e9missionnaire, je le conc\u00e8de. Mais quand m\u00eame ! <!--more--><\/p>\n<p>Voici la chronique que France Inter ne diffusera pas :<br \/>\n<iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/UUvmE6pEgLs\" frameborder=\"0\" width=\"560\" height=\"315\"><\/iframe><\/p>\n<p>Nagui ayant jug\u00e9 que cette d\u00e9fense de l&rsquo;abstention \u00ab\u00a0faisait le jeu du FN\u00a0\u00bb, le chroniqueur Pierre-Emmanuel Barr\u00e9 a quitt\u00e9 France Inter. On lui aurait \u00ab\u00a0demand\u00e9 de ne pas faire cette chronique\u00a0\u00bb :<\/p>\n<blockquote><p>\u00ab\u00a0Quand on me demande de ne pas faire une chronique, je d\u00e9missionne. Je n&rsquo;aime pas \u00eatre censur\u00e9.\u00a0\u00bb<\/p><\/blockquote>\n<p>A quoi Nagui oppose sa version :<\/p>\n<blockquote><p>\u00ab\u00a0Sur le coup, je lui ai simplement dit qu&rsquo;il n&rsquo;\u00e9tait pas clair sur l&rsquo;abstention. Qu&rsquo;il casse Macron ou Le Pen, OK. Mais qu&rsquo;il encourage l&rsquo;abstention, c&rsquo;est faire le jeu du FN.\u00a0Mais il a pr\u00e9f\u00e9r\u00e9 ne pas venir \u00e0 l&rsquo;antenne. Apr\u00e8s l&rsquo;\u00e9mission, je lui ai finalement propos\u00e9 de faire sa chronique demain (jeudi 27 avril) sans changer une ligne. Et moi, j&rsquo;aurais ajout\u00e9 un mot pour dire d&rsquo;aller voter. Au lieu de \u00e7a, il a pr\u00e9f\u00e9r\u00e9 le faire sur internet. Libre \u00e0 lui.\u00a0\u00bb<\/p><\/blockquote>\n<p>Lui a-t-on, ou non, \u00ab\u00a0demand\u00e9 de ne pas faire cette chronique\u00a0\u00bb ? Le fait que Barr\u00e9 ait choisi de d\u00e9missionner de l&rsquo;antenne, ce qui n&rsquo;est tout de m\u00eame pas une petit d\u00e9cision, sugg\u00e8re tr\u00e8s clairement que Nagui \u00e9dulcore la r\u00e9alit\u00e9. Un texte publi\u00e9 sur Facebook par trois humoristes de France Inter confirme que la chronique a \u00e9t\u00e9 <a href=\"http:\/\/www.sudouest.fr\/2017\/04\/27\/pour-d-autres-humoristes-de-france-inter-pierre-emmanuel-barre-n-a-pas-ete-censure-3402448-4693.php\" target=\"_blank\" rel=\"noopener\">\u00ab\u00a0refus\u00e9e, sous le coup d&rsquo;une r\u00e9action \u00e9pidermique (r\u00e9action que nous pouvons comprendre)\u00a0\u00bb<\/a>, avant que Nagui se ravise en constatant la cons\u00e9quence de son interdiction.<\/p>\n<p>Mais ce qui m&rsquo;a int\u00e9ress\u00e9e, c&rsquo;est la mani\u00e8re dont les m\u00e9dias ont rendu compte de cette affaire.<\/p>\n<p>Partout, on lit que la chronique de P-E Barr\u00e9 a \u00e9t\u00e9 \u00ab\u00a0refus\u00e9e\u00a0\u00bb:<\/p>\n<p><a href=\"http:\/\/blog.causeur.fr\/lavoixdenosmaitres\/files\/2017\/04\/refus\u00e91.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-464\" title=\"refus\u00e91\" src=\"http:\/\/blog.causeur.fr\/lavoixdenosmaitres\/files\/2017\/04\/refus\u00e91.jpg\" alt=\"\" width=\"648\" height=\"155\" srcset=\"https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-content\/uploads\/sites\/27\/2017\/04\/refus\u00e91.jpg 648w, https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-content\/uploads\/sites\/27\/2017\/04\/refus\u00e91-300x71.jpg 300w, https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-content\/uploads\/sites\/27\/2017\/04\/refus\u00e91-500x119.jpg 500w\" sizes=\"auto, (max-width: 648px) 100vw, 648px\" \/><\/a><a href=\"http:\/\/blog.causeur.fr\/lavoixdenosmaitres\/files\/2017\/04\/refus\u00e931.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-466\" title=\"refus\u00e93\" src=\"http:\/\/blog.causeur.fr\/lavoixdenosmaitres\/files\/2017\/04\/refus\u00e931.jpg\" alt=\"\" width=\"921\" height=\"292\" srcset=\"https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-content\/uploads\/sites\/27\/2017\/04\/refus\u00e931.jpg 921w, https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-content\/uploads\/sites\/27\/2017\/04\/refus\u00e931-300x95.jpg 300w, https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-content\/uploads\/sites\/27\/2017\/04\/refus\u00e931-500x158.jpg 500w\" sizes=\"auto, (max-width: 921px) 100vw, 921px\" \/><\/a>Or, un sketch radio-diffus\u00e9 n&rsquo;est pas un manuscrit que l&rsquo;on soumet \u00e0 un \u00e9diteur et qui peut donc \u00eatre rejet\u00e9. <a href=\"http:\/\/www.francetvinfo.fr\/elections\/presidentielle\/l-humoriste-pierre-emmanuel-barre-quitte-france-inter-pour-un-sketch-pro-abstention-refuse_2164118.html\" target=\"_blank\" rel=\"noopener\">Comme le rappelle Laurence Bloch,<\/a> la directrice de la station :<\/p>\n<blockquote><p>les chroniqueurs sont absolument libres<\/p><\/blockquote>\n<p>On n&rsquo;est donc pas cens\u00e9 emp\u00eacher la diffusion de leur texte pour des raisons id\u00e9ologiques, ce qui est la d\u00e9finition m\u00eame de la censure.<\/p>\n<p>Mais tout le monde est-il au clair avec cette d\u00e9finition ? Observons cette phrase de Nagui :<\/p>\n<blockquote><p>Ce n&rsquo;est pas de la censure, surtout par rapport \u00e0 la vraie censure qui risque d&rsquo;arriver si Le Pen passe.<\/p><\/blockquote>\n<p>J&rsquo;avoue go\u00fbter particuli\u00e8rement le \u00ab\u00a0surtout par rapport \u00e0\u00a0\u00bb. En est-ce ou non ? Si l&rsquo;on comprend bien, la vraie censure, c&rsquo;est quand ce sont les m\u00e9chants qui censurent. Quand c&rsquo;est nous, ce n&rsquo;est pas de la vraie censure.<\/p>\n<div id=\"ligne\"><\/div>\n<p>Au demeurant, je pense que Nagui se trompe. La popularit\u00e9 de Le Pen doit tellement \u00e0 l&rsquo;hostilit\u00e9 que lui vouent les m\u00e9dias comme France Inter que, si elle est \u00e9lue, elle aura, au contraire, int\u00e9r\u00eat \u00e0 les laisser continuer comme avant. Elle aurait tout \u00e0 perdre \u00e0 les censurer. Ils se retrouveront dans la position de Cic\u00e9ron, qui avait pens\u00e9 \u00e0 tort que Jules C\u00e9sar le ferait assassiner par vengeance et qui enrageait en constatant que sa propre vie \u00e9tait, aux yeux de tous, la preuve de la cl\u00e9mence de son pire ennemi, fin propagandiste.<\/p>\n<p>Reprenons: quand France Inter censure la chronique de Pierre-Emmanuel Barr\u00e9, ce n&rsquo;est pas de la censure. Or, ce qui surprend (ou pas), c&rsquo;est que tous les m\u00e9dias sont d&rsquo;accord pour dire que ce n&rsquo;est pas de la censure.<\/p>\n<p>Voyez plut\u00f4t :<\/p>\n<p><a href=\"http:\/\/blog.causeur.fr\/lavoixdenosmaitres\/files\/2017\/04\/estimant1.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-467\" title=\"estimant1\" src=\"http:\/\/blog.causeur.fr\/lavoixdenosmaitres\/files\/2017\/04\/estimant1.jpg\" alt=\"\" width=\"405\" height=\"112\" srcset=\"https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-content\/uploads\/sites\/27\/2017\/04\/estimant1.jpg 405w, https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-content\/uploads\/sites\/27\/2017\/04\/estimant1-300x82.jpg 300w\" sizes=\"auto, (max-width: 405px) 100vw, 405px\" \/><\/a><a href=\"http:\/\/blog.causeur.fr\/lavoixdenosmaitres\/files\/2017\/04\/estimant2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-468\" title=\"estimant2\" src=\"http:\/\/blog.causeur.fr\/lavoixdenosmaitres\/files\/2017\/04\/estimant2.jpg\" alt=\"\" width=\"958\" height=\"206\" srcset=\"https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-content\/uploads\/sites\/27\/2017\/04\/estimant2.jpg 958w, https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-content\/uploads\/sites\/27\/2017\/04\/estimant2-300x64.jpg 300w, https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-content\/uploads\/sites\/27\/2017\/04\/estimant2-500x107.jpg 500w\" sizes=\"auto, (max-width: 958px) 100vw, 958px\" \/><\/a><a href=\"http:\/\/blog.causeur.fr\/lavoixdenosmaitres\/files\/2017\/04\/estimant3.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-469\" title=\"estimant3\" src=\"http:\/\/blog.causeur.fr\/lavoixdenosmaitres\/files\/2017\/04\/estimant3.jpg\" alt=\"\" width=\"472\" height=\"62\" srcset=\"https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-content\/uploads\/sites\/27\/2017\/04\/estimant3.jpg 472w, https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-content\/uploads\/sites\/27\/2017\/04\/estimant3-300x39.jpg 300w\" sizes=\"auto, (max-width: 472px) 100vw, 472px\" \/><\/a><a href=\"http:\/\/blog.causeur.fr\/lavoixdenosmaitres\/files\/2017\/04\/estimant4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-470\" title=\"estimant4\" src=\"http:\/\/blog.causeur.fr\/lavoixdenosmaitres\/files\/2017\/04\/estimant4.jpg\" alt=\"\" width=\"642\" height=\"152\" srcset=\"https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-content\/uploads\/sites\/27\/2017\/04\/estimant4.jpg 642w, https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-content\/uploads\/sites\/27\/2017\/04\/estimant4-300x71.jpg 300w, https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-content\/uploads\/sites\/27\/2017\/04\/estimant4-500x118.jpg 500w\" sizes=\"auto, (max-width: 642px) 100vw, 642px\" \/><\/a>Il \u00ab\u00a0s&rsquo;estime\u00a0\u00bb censur\u00e9. C&rsquo;est une appr\u00e9ciation personnelle. Comme si l&rsquo;on ne pouvait objectivement nommer le probl\u00e8me. Pourtant, la raison invoqu\u00e9e par Nagui est claire : cette chronique \u00ab\u00a0faisait le jeu de\u00a0\u00bb.<\/p>\n<p>Tous les m\u00e9dias acceptent donc tacitement la distinction entre vraie et fausse censure, c&rsquo;est-\u00e0-dire entre censure interdite et censure autoris\u00e9e, formul\u00e9e par Nagui.<\/p>\n<p>On conclura avec cette citation tir\u00e9e de la tribune des trois ex-coll\u00e8gues de P.-E. Barr\u00e9:<\/p>\n<blockquote><p>Soup\u00e7onner la radio de service public de censure est une chose grave.<\/p><\/blockquote>\n<p>Comprenez bien: ce qui est grave n&rsquo;est pas que la radio de service public censure, mais qu&rsquo;on la soup\u00e7onne de censurer. Par \u00ab\u00a0chose grave\u00a0\u00bb, il faut donc ici entendre \u00ab\u00a0chose interdite\u00a0\u00bb. Nous n&rsquo;avons pas le droit de soup\u00e7onner cette radio de pratiquer la censure. Si l&rsquo;on en croit Nagui, elle ne pratique en effet que la fausse censure, c&rsquo;est-\u00e0-dire la bonne.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comme disait Musset, il faut qu&rsquo;une porte soit ouverte ou ferm\u00e9e. Dans cet article, je prends la d\u00e9fense d&rsquo;un chroniqueur de France Inter. D\u00e9missionnaire, je le conc\u00e8de. Mais quand m\u00eame !<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[190,161,136,104,188,189],"class_list":{"0":"post-461","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-articles","7":"tag-abstention","8":"tag-censure","9":"tag-election-presidentielle","10":"tag-france-inter","11":"tag-nagui","12":"tag-pierre-emmanuel-barre"},"_links":{"self":[{"href":"https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-json\/wp\/v2\/posts\/461","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-json\/wp\/v2\/comments?post=461"}],"version-history":[{"count":0,"href":"https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-json\/wp\/v2\/posts\/461\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-json\/wp\/v2\/media?parent=461"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-json\/wp\/v2\/categories?post=461"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-json\/wp\/v2\/tags?post=461"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}