{"id":586,"date":"2017-09-12T21:00:26","date_gmt":"2017-09-12T21:00:26","guid":{"rendered":"http:\/\/blog.causeur.fr\/lavoixdenosmaitres\/?p=586"},"modified":"2021-04-23T15:35:01","modified_gmt":"2021-04-23T13:35:01","slug":"soumission-ordinaire-sur-bfm-tv-salhia-brakhlia-et-les-interdits-alimentaires","status":"publish","type":"post","link":"https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/soumission-ordinaire-sur-bfm-tv-salhia-brakhlia-et-les-interdits-alimentaires-586","title":{"rendered":"Soumission ordinaire sur BFM TV : Salhia Brakhlia et les interdits alimentaires"},"content":{"rendered":"<p><a href=\"http:\/\/blog.causeur.fr\/lavoixdenosmaitres\/files\/2017\/09\/oeil-de-salhia5.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-594\" src=\"http:\/\/blog.causeur.fr\/lavoixdenosmaitres\/files\/2017\/09\/oeil-de-salhia5.jpg\" alt=\"oeil de salhia5\" width=\"899\" height=\"465\" srcset=\"https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-content\/uploads\/sites\/27\/2017\/09\/oeil-de-salhia5.jpg 899w, https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-content\/uploads\/sites\/27\/2017\/09\/oeil-de-salhia5-300x155.jpg 300w, https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-content\/uploads\/sites\/27\/2017\/09\/oeil-de-salhia5-768x397.jpg 768w, https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-content\/uploads\/sites\/27\/2017\/09\/oeil-de-salhia5-500x259.jpg 500w\" sizes=\"auto, (max-width: 899px) 100vw, 899px\" \/><\/a>Je sentais que cette Salhia Brakhlia avait un gros potentiel. Elle ne m&rsquo;a pas d\u00e9\u00e7ue.<!--more--><\/p>\n<p>Elle nous a offert ceci\u00a0:<\/p>\n<div style=\"display: block; position: relative;\">\n<div style=\"padding-top: 56.25%;\"><iframe loading=\"lazy\" style=\"width: 100%; height: 100%; position: absolute; top: 0px; bottom: 0px; right: 0px; left: 0px; border: none;\" src=\"http:\/\/www.bfmtv.com\/static\/nxt-video\/player.html?video=5565764866001&amp;brand=BFMTV&amp;url=http:\/\/www.bfmtv.com\/mediaplayer\/video\/l-oeil-de-salhia-la-fete-du-cochon-d-hayange-977975.html\" width=\"300\" height=\"150\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p>On voit qu\u2019elle a \u00e9t\u00e9 form\u00e9e au Petit Journal, son transfert lui a d\u2019ailleurs valu <a href=\"http:\/\/www.liberation.fr\/ecrans\/2015\/08\/31\/joie-cathodique_1373056\">un portrait perfide sign\u00e9 <\/a><em>Lib\u00e9ration <\/em>: Salhia, c\u2019est la fille qui \u00ab\u00a0l\u00e2che des banalit\u00e9s\u00a0\u00bb et encha\u00eene les \u00ab\u00a0poncifs dignes des plus grands champions de la langue de bois politicienne\u00a0\u00bb, et qui trouve que tout le monde est \u00ab\u00a0super sympa\u00a0\u00bb. Apparemment, les gens qui vont \u00e0 la f\u00eate du cochon, non, elle ne les trouve pas super sympas.<\/p>\n<p>Comme d\u2019habitude, j\u2019ai attendu un peu de voir qui allait en dire quoi. Je m\u2019attendais \u00e0 ce que <a href=\"http:\/\/ripostelaique.com\/bfm-tv-reportage-putassier-de-salhia-brakhlia-sur-la-fete-du-cochon-dhayange.html\">Riposte La\u00efque<\/a>, <a href=\"http:\/\/www.bvoltaire.fr\/fete-cochon-a-hayange-petit-dobjectivite-merci-deviter-bfm-tv\/\">Boulevard Voltaire<\/a>, <a href=\"http:\/\/resistancerepublicaine.eu\/2017\/09\/09\/salhia-brakhlia-de-bfm-ne-sindigne-pas-de-savoir-que-tout-le-monde-mange-halal-sans-le-savoir\/\">R\u00e9sistance R\u00e9publicaine<\/a> et <a href=\"https:\/\/www.tvlibertes.com\/2017\/09\/08\/18975\/pour-bfm-rien-nest-bon-dans-le-cochon\">TV Libert\u00e9s<\/a> en parlassent.<\/p>\n<p>Mais j\u2019attendais surtout l\u2019article du <em>Monde,<\/em> de <em>M\u00e9diapart,<\/em> du <em>Huffington Post<\/em> ou que sais-je encore qui titrerait\u00a0: \u00ab\u00a0D\u00e9cha\u00eenement raciste contre une journaliste de BFM TV\u00a0\u00bb et nous expliquerait que les m\u00e9chants fachos s\u2019en prenaient \u00e0 une gentille fifille qui n\u2019avait fait que son travail.<\/p>\n<p>Toutefois, cet article tarde \u00e0 venir et sans doute ne viendra-t-il pas. Pourquoi\u00a0?<\/p>\n<p>La r\u00e9ponse est dans cette image\u00a0:<\/p>\n<p><a href=\"http:\/\/blog.causeur.fr\/lavoixdenosmaitres\/files\/2017\/09\/oeil-de-salhia.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-587\" src=\"http:\/\/blog.causeur.fr\/lavoixdenosmaitres\/files\/2017\/09\/oeil-de-salhia.jpg\" alt=\"oeil de salhia\" width=\"877\" height=\"441\" srcset=\"https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-content\/uploads\/sites\/27\/2017\/09\/oeil-de-salhia.jpg 877w, https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-content\/uploads\/sites\/27\/2017\/09\/oeil-de-salhia-300x151.jpg 300w, https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-content\/uploads\/sites\/27\/2017\/09\/oeil-de-salhia-768x386.jpg 768w, https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-content\/uploads\/sites\/27\/2017\/09\/oeil-de-salhia-500x251.jpg 500w\" sizes=\"auto, (max-width: 877px) 100vw, 877px\" \/><\/a>Jean-Baptiste Boursier n\u2019est pas tr\u00e8s \u00e0 l\u2019aise avec le document de Salhia. C\u2019est qu\u2019il n\u2019est pas b\u00eate et il a fort bien compris ce que n\u2019importe qui peut constater en regardant ce reportage\u00a0: <strong>ce qui g\u00eane Salhia, c\u2019est bien moins le FN que le cochon<\/strong>.<\/p>\n<p>Ce n\u2019est pas d\u2019embl\u00e9e \u00e9vident\u00a0: <strong>\u00ab\u00a0des f\u00eates du cochon, il y en a plusieurs en France, c\u2019est normal\u00a0!\u00a0\u00bb<\/strong>, dit Salhia (00\u00a0:12)<\/p>\n<p>Notez, elle a bien dit\u00a0: \u00ab\u00a0c\u2019est normal\u00a0\u00bb. J&rsquo;ai envie de lui demander pourquoi, selon elle, c&rsquo;est normal. Parce qu&rsquo;elle va ensuite s&rsquo;\u00e9vertuer \u00e0 montrer le contraire.<\/p>\n<p>Salhia Brakhlia indique que la sp\u00e9cificit\u00e9 g\u00eanante de la f\u00eate d\u2019Hayange, c\u2019est son caract\u00e8re excessivement politis\u00e9. Pour l\u2019instant, pas de probl\u00e8me. <strong>Elle ne semble pas vouloir s\u2019en prendre \u00e0 la f\u00eate du cochon en soi mais seulement \u00e0 sa r\u00e9cup\u00e9ration politique.<\/strong> J\u2019adh\u00e8re.<\/p>\n<p>Mais dans ce cas, comment se justifie la s\u00e9quence qui va de 00\u00a0: 26 \u00e0 01\u00a0:07\u00a0?<\/p>\n<blockquote><p>Logiquement la mascotte, c\u2019est un cochon\u2026 qui met de l\u2019ambiance, hein\u00a0? Et non, ils n\u2019ont pas fait dans la lourdeur\u00a0: apr\u00e8s les affiches, le ballon gonflable. On a vu un traiteur \u00e0 la t\u00eate de cochon. Au menu, justement, bi\u00e8re et tout ce qui peut \u00eatre comestible dans le cochon. Et pour le dessert, on reste dans la th\u00e9matique avec des viennoiseries t\u00eate de cochon et des \u00e9clairs en forme de cochon.<\/p><\/blockquote>\n<p>Moi, les images m\u2019ont mis l\u2019eau \u00e0 la bouche et j\u2019ai trouv\u00e9 g\u00e9nial qu\u2019ils aient jou\u00e9 la carte du cochon jusque dans le sucr\u00e9. Mais le ton moqueur de Salhia Brakhlia sugg\u00e8re de sa part une forte d\u00e9sapprobation, comme le confirme sa mine :<\/p>\n<p><a href=\"http:\/\/blog.causeur.fr\/lavoixdenosmaitres\/files\/2017\/09\/oeil-de-salhia2.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-588\" src=\"http:\/\/blog.causeur.fr\/lavoixdenosmaitres\/files\/2017\/09\/oeil-de-salhia2.jpg\" alt=\"oeil de salhia2\" width=\"227\" height=\"255\" \/><\/a>Pourtant, on n\u2019a pas encore vu de n\u00e9o-nazi. On n\u2019a vu que des cochons.<\/p>\n<p>Juste pour info, les cochons roses du p\u00e2tissier ne sont pas des \u00ab\u00a0\u00e9clairs\u00a0\u00bb, M\u2019dame Salhia\u00a0: c\u2019est de la p\u00e2te d\u2019amande fourr\u00e9e (les fameux \u00ab\u00a0petits cochons de la St Antoine\u00a0\u00bb). C\u2019est d\u00e9licieux. Et vous pouvez en manger, vous savez, Salhia, parce que ce n\u2019est pas <em>vraiment<\/em> du cochon, c\u2019est juste <em>en forme de<\/em> cochon. Mais <a href=\"https:\/\/www.yabiladi.com\/forum\/gateau-d-anniversaire-forme-peppa-halal-90-5717015.html\">il y en a qui font du z\u00e8le, apparemment<\/a>, (et il faut croire que notre Salhia est du nombre). J&rsquo;ai trouv\u00e9 ceci sur un forum :<\/p>\n<p><a href=\"http:\/\/blog.causeur.fr\/lavoixdenosmaitres\/files\/2017\/09\/oeil-de-salhia4.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-590\" src=\"http:\/\/blog.causeur.fr\/lavoixdenosmaitres\/files\/2017\/09\/oeil-de-salhia4.jpg\" alt=\"oeil de salhia4\" width=\"649\" height=\"194\" srcset=\"https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-content\/uploads\/sites\/27\/2017\/09\/oeil-de-salhia4.jpg 649w, https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-content\/uploads\/sites\/27\/2017\/09\/oeil-de-salhia4-300x90.jpg 300w, https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-content\/uploads\/sites\/27\/2017\/09\/oeil-de-salhia4-500x149.jpg 500w\" sizes=\"auto, (max-width: 649px) 100vw, 649px\" \/><\/a>Notez que \u00ab\u00a0on lui as bien expliquer que c\u2019\u00e9tait autoriser\u00a0\u00bb. Donc c\u2019est pas interdit.<\/p>\n<p>L\u00e0 o\u00f9 cela devient vraiment g\u00eanant pour Salhia, c\u2019est quand elle demande \u00e0 un charcutier ce qu\u2019on peut manger \u00e0 la f\u00eate du cochon quand on n\u2019aime pas le cochon ; elle demandera ensuite au maire FN s\u2019il compte organiser une f\u00eate du maqrouth \u00e0 Hayange.<\/p>\n<p><a href=\"http:\/\/blog.causeur.fr\/lavoixdenosmaitres\/files\/2017\/09\/maqrouth.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-593 alignright\" src=\"http:\/\/blog.causeur.fr\/lavoixdenosmaitres\/files\/2017\/09\/maqrouth.jpg\" alt=\"maqrouth\" width=\"283\" height=\"283\" srcset=\"https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-content\/uploads\/sites\/27\/2017\/09\/maqrouth.jpg 900w, https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-content\/uploads\/sites\/27\/2017\/09\/maqrouth-150x150.jpg 150w, https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-content\/uploads\/sites\/27\/2017\/09\/maqrouth-300x300.jpg 300w, https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-content\/uploads\/sites\/27\/2017\/09\/maqrouth-768x768.jpg 768w, https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-content\/uploads\/sites\/27\/2017\/09\/maqrouth-32x32.jpg 32w, https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-content\/uploads\/sites\/27\/2017\/09\/maqrouth-50x50.jpg 50w, https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-content\/uploads\/sites\/27\/2017\/09\/maqrouth-64x64.jpg 64w, https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-content\/uploads\/sites\/27\/2017\/09\/maqrouth-96x96.jpg 96w, https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-content\/uploads\/sites\/27\/2017\/09\/maqrouth-128x128.jpg 128w\" sizes=\"auto, (max-width: 283px) 100vw, 283px\" \/><\/a>Et non, pas de f\u00eate du maqrouth pr\u00e9vue \u00e0 Hayange. Salhia pas contente.<\/p>\n<p>Vous trouvez \u00e7a d\u00e9bile\u00a0? Moi, <strong>je crois que Salhia Brakhlia vient d\u2019\u00e9laborer un concept d&rsquo;\u00e9mission perp\u00e9tuellement d\u00e9clinable<\/strong>. Elle doit pouvoir tenir toute l\u2019ann\u00e9e comme \u00e7a\u00a0:<\/p>\n<p>Au fest-noz de Brest\u00a0: quoi, vous ne servez pas de choucroute alsacienne\u00a0?<\/p>\n<p>A la f\u00eate du foie gras de Pau\u00a0: pas de moules \u00e0 la normande\u00a0?<\/p>\n<p>A la f\u00eate de l&rsquo;escargot de Bourgogne\u00a0: comment, vous ne proposez pas de calissons d\u2019Aix\u00a0?<\/p>\n<p>Salhia n\u2019ira pas \u00e0 la f\u00eate de l&rsquo;escargot demander ce qu\u2019on peut y d\u00e9guster si l\u2019on n\u2019aime pas les escargots. <strong>Pourtant, les escargots, c\u2019est beaucoup plus discriminant que le cochon\u00a0: il faudrait faire une enqu\u00eate d\u2019opinion, mais je suis certaine que les mangeurs d\u2019escargots sont bien moins nombreux que les mangeurs de porc. Donc le vrai scandale est \u00e0 la f\u00eate de l&rsquo;escargot, pas \u00e0 la f\u00eate du cochon<\/strong>. Comme dit Salhia\u00a0: \u00ab\u00a0\u00e7a \u00e9carte pas mal de gens\u00a0\u00bb.<\/p>\n<p>J&rsquo;ai cherch\u00e9 \u00e0 savoir si la consommation d&rsquo;escargots est halal. J&rsquo;ai lu des kilom\u00e8tres de forums musulmans sans trouver la r\u00e9ponse. Et puis, j&rsquo;ai trouv\u00e9 cette vid\u00e9o et l\u00e0&#8230; je n&rsquo;ai rien compris :<br \/>\n<iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/8vP86EGjvyg\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p>C&rsquo;est dommage parce que j&rsquo;aimerais bien savoir.<\/p>\n<p>Salhia dit au charcutier qu\u2019elle \u00ab\u00a0n\u2019aime pas le cochon\u00a0\u00bb. L\u00e0, j\u2019ai envie de lui dire comme aux enfants : \u00ab\u00a0comment peux-tu savoir que tu n\u2019aimes pas, si tu n\u2019y as pas go\u00fbt\u00e9\u00a0?\u00a0\u00bb. Par exemple, moi, je sais que je n\u2019aime pas les escargots de Bourgogne. Mais Salhia Brakhlia ne sait pas si elle aime le travers de porc. Elle est juste cochonophobe par principe.<\/p>\n<p>Quand elle dit que \u00ab\u00a0\u00e7a \u00e9carte pas mal de gens\u00a0\u00bb, elle pr\u00e9cise\u00a0: \u00ab\u00a0je pense par exemple aux musulmans ou aux personnes de confession juive, pour ne citer qu\u2019eux\u00a0\u00bb. <strong>J\u2019adore \u00ab\u00a0personnes de confession juive\u00a0\u00bb\u00a0: \u00e7a doit \u00e9corcher la bouche de dire \u00ab\u00a0les Juifs\u00a0\u00bb. \u00c7a me fait penser aux cathos qui disent \u00ab\u00a0personnes homosexuelles\u00a0\u00bb pour ne pas r\u00e9duire les gens \u00e0 leur vice.<\/strong> Salhia, c\u2019est pareil, elle ne veut pas r\u00e9duire les Juifs \u00e0 leur vice qui est d\u2019\u00eatre juifs. En revanche, les \u00ab\u00a0musulmans\u00a0\u00bb ne sont pas des \u00ab\u00a0personnes de confession musulmane\u00a0\u00bb.<\/p>\n<p>On remarque qu\u2019elle ne pense pas aux v\u00e9g\u00e9tariens. Elle n\u2019y pense m\u00eame pas du tout puisqu\u2019elle a demand\u00e9 au charcutier\u00a0ce qu\u2019elle pouvait manger \u00ab\u00a0comme viande\u00a0\u00bb si elle ne prenait pas de cochon. Les v\u00e9g\u00e9tariens ne peuvent pas manger de viande du tout, donc la f\u00eate de Salhia ne leur conviendrait pas mieux. Et puis les personnes allergiques au gluten, elle y a pens\u00e9, Salhia\u00a0? Eux, ce sont les desserts qu\u2019ils ne peuvent pas manger \u00e0 la f\u00eate du cochon. Pareil pour les gens allergiques aux \u0153ufs. Et puis, imaginons qu\u2019on ait pr\u00e9vu un stand pour les cochonophobes, je pense que Salhia ne serait pas plus satisfaite parce que les steaks ne seraient pas forc\u00e9ment certifi\u00e9s halal. Du coup, \u00ab\u00a0\u00e7a \u00e9carte pas mal de gens\u00a0\u00bb.<\/p>\n<div id=\"ligne\"><\/div>\n<p>Bon ensuite, Salhia n\u2019est pas contente parce qu\u2019elle n\u2019arrive pas \u00e0 trouver une oreille compatissante pour son probl\u00e8me: \u00ab\u00a0\u00e7a vous d\u00e9range pas?\u00a0\u00bb On remarque que les gens sont polis: ils acceptent de lui r\u00e9pondre, en d\u00e9pit de son regard que l&rsquo;on devine charg\u00e9 tout \u00e0 la fois de sarcasme, de m\u00e9pris et de d\u00e9testation. Les gens lui r\u00e9pondent, et avec le sourire, m\u00eame les gros costauds tatou\u00e9s. Pourtant, ils auraient des raisons de s&rsquo;\u00e9nerver. Alors que Juifs et v\u00e9g\u00e9tariens ne se sentent tout simplement pas concern\u00e9s par la f\u00eate du cochon, <strong>Salhia, elle, est dans une posture militante, celle de l&rsquo;intimidation : il s&rsquo;agit de susciter la honte chez ceux qui osent manger du porc quand d&rsquo;autres ont fait le choix de n&rsquo;en pas manger<\/strong>, de leur faire sentir que cette f\u00eate, parce qu&rsquo;elle est discriminante, ne devrait pas exister.<\/p>\n<p><strong>Elle n\u2019est pas contente non plus quand elle entend le maire d\u00e9noncer le terrorisme et faire ovationner les f\u00e9ministes alg\u00e9riennes qui refusent le burkini<\/strong>. L\u00e0, pourtant, on ne voit pas le probl\u00e8me.<\/p>\n<p>Quant \u00e0 la s\u00e9quence du salut nazi, voici ce que j\u2019en pense\u00a0:<\/p>\n<ol>\n<li>Salhia Braklia confond la droite et la gauche puisqu\u2019elle dit que le monsieur faisant le salut nazi est \u00e0 droite sur l\u2019image, alors qu\u2019il est \u00e0 gauche.<\/li>\n<li>Ce monsieur doit \u00eatre un nazi d\u00e9butant\u00a0: il l\u00e8ve le bras gauche au lieu du droit. D\u00e9cid\u00e9ment.<\/li>\n<li>Pour que j\u2019y croie, il me faut cinq ou six bonshommes qui font des saluts nazis. Dans ce type de reportages, je me m\u00e9fie \u00e9norm\u00e9ment : <strong>souvent, il ne s\u2019agit pas de montrer ce qu\u2019on voit mais de trouver ce qu\u2019on est venu chercher<\/strong>. Salhia est venue pour filmer un salut nazi. Faute de mieux, elle a trouv\u00e9 un nazi \u00e0 deux balles qui se trompe de bras. Mais peut-\u00eatre a-t-elle embauch\u00e9 un de ses potes pour jouer les nazis, c\u2019est une pratique tr\u00e8s courante. J\u2019avais d\u00e9j\u00e0 eu l\u2019occasion de parler du <a href=\"http:\/\/blog.causeur.fr\/lavoixdenosmaitres\/c8-en-infiltration-au-fnj-00401.html\">faux nazi introduit par des journalistes allemands dans une section r\u00e9gionale du FN et maladroitement \u00ab\u00a0out\u00e9\u00a0\u00bb par un journaliste de C8 infiltr\u00e9 au m\u00eame moment dans la m\u00eame section<\/a>.<\/li>\n<\/ol>\n<p>Le m\u00e9tier de Salhia est difficile. Trouver chaque jour de nouvelles id\u00e9es pour sa rubrique, oh lala\u00a0! Alors, je pense que nous pouvons l\u2019aider en lui sugg\u00e9rant des \u00e9v\u00e9nements int\u00e9ressants pour elle, parce qu\u2019elle n\u2019aurait pas \u00e0 se fatiguer\u00a0: elle pourrait refourguer exactement le m\u00eame reportage. Ce qu\u2019il faut, c\u2019est des traditions fran\u00e7aises bien islamo-incompatibles\u2026 et la probabilit\u00e9 de rencontrer quelques n\u00e9o-nazis ou assimil\u00e9s. Que cette probabilit\u00e9 soit faible importe peu\u00a0: elle a l\u2019\u0153il, Salhia\u00a0! <strong>Alors, je sugg\u00e8re\u00a0: la f\u00eate des vendanges, la f\u00eate du cognac, la f\u00eate de l\u2019armagnac, le champagne en f\u00eate, la f\u00eate du cidre et du calva, les f\u00eates vertes et or de la chartreuse, le festival du vin de Bordeaux, le festival des vins d\u2019Alsace, la f\u00eate des vins et terroirs, la c\u00e9r\u00e9monie de la tripi\u00e8re d\u2019or, le mondial du saucisson, la f\u00eate du porc noir, la foire au jambon, la f\u00eate du boudin, la f\u00eate de la charcuterie et bien s\u00fbr\u2026 le festival du cochon.<\/strong><\/p>\n<p><a href=\"http:\/\/blog.causeur.fr\/lavoixdenosmaitres\/files\/2017\/09\/Festival_du_cochon_de_Sainte-Perp\u00e9tue.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-592\" src=\"http:\/\/blog.causeur.fr\/lavoixdenosmaitres\/files\/2017\/09\/Festival_du_cochon_de_Sainte-Perp\u00e9tue.png\" alt=\"Festival_du_cochon_de_Sainte-Perp\u00e9tue\" width=\"473\" height=\"268\" srcset=\"https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-content\/uploads\/sites\/27\/2017\/09\/Festival_du_cochon_de_Sainte-Perp\u00e9tue.png 473w, https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-content\/uploads\/sites\/27\/2017\/09\/Festival_du_cochon_de_Sainte-Perp\u00e9tue-300x170.png 300w\" sizes=\"auto, (max-width: 473px) 100vw, 473px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Je sentais que cette Salhia Brakhlia avait un gros potentiel. Elle ne m&rsquo;a pas d\u00e9\u00e7ue.<\/p>\n","protected":false},"author":7,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9],"tags":[92,243,176,237,242],"class_list":{"0":"post-586","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-articles","7":"tag-bfm-tv","8":"tag-fete-du-cochon","9":"tag-fn","10":"tag-islam-islamisme","11":"tag-salhia-brakhlia"},"_links":{"self":[{"href":"https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-json\/wp\/v2\/posts\/586","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-json\/wp\/v2\/comments?post=586"}],"version-history":[{"count":0,"href":"https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-json\/wp\/v2\/posts\/586\/revisions"}],"wp:attachment":[{"href":"https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-json\/wp\/v2\/media?parent=586"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-json\/wp\/v2\/categories?post=586"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.causeur.fr\/lavoixdenosmaitres\/wp-json\/wp\/v2\/tags?post=586"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}